{"id":91329,"date":"2023-08-07T20:54:05","date_gmt":"2023-08-07T20:54:05","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=91329"},"modified":"2023-08-07T20:54:05","modified_gmt":"2023-08-07T20:54:05","slug":"fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/","title":{"rendered":"Fiscal dijo que hubo \u00abviolencia de g\u00e9nero\u00bb en el crimen de una mujer en Coronel Dorrego en 2022"},"content":{"rendered":"<p>El fiscal del juicio por jurados que comenz\u00f3 hoy por el crimen de Natal\u00ed Rodr\u00edguez, hallada estrangulada en marzo del a\u00f1o pasado en su casa del partido bonaerense de Coronel Dorrego, consider\u00f3 hoy que durante la investigaci\u00f3n qued\u00f3 probada la autor\u00eda del asesinato por parte del exnovio de la v\u00edctima, y que est\u00e1 convencido que el hecho se cometi\u00f3 en un contexto de \u00abviolencia de g\u00e9nero\u00bb.<!--more--><\/p>\n<p>\u201cNo est\u00e1 en tela de juicio quien es el autor de este homicidio\u201d, dijo ante los 12 ciudadanos que hoy fueron elegidos para integrar el jurado popular el fiscal Jorge Viego en su alegato de apertura, en el que explic\u00f3 que los testigos que declarar\u00e1n en las audiencias \u00abvan a demostrar que realmente existi\u00f3 violencia de g\u00e9nero previo a este hecho\u201d por parte del acusado a Sebasti\u00e1n Calvo (34).<\/p>\n<p>El juicio por jurados fue presidido por el juez t\u00e9cnico Eduardo d&#8217;Empaire, titular del Tribunal Oral en lo Criminal (TOC) 3 de Bah\u00eda Blanca, y el acusado Calvo lleg\u00f3 al debate detenido y acusado del delito de \u00abhomicidio calificado por haber sido cometido por un hombre contra una mujer mediando violencia de g\u00e9nero\u00bb, en perjuicio su exnovia Rodr\u00edguez.<\/p>\n<p>El fiscal le explic\u00f3 al jurado popular que, como el acusado confes\u00f3 haber cometido el crimen, \u00abno est\u00e1 en tela de juicio qui\u00e9n fue el autor de este homicidio, pero lo que hay que dilucidar es si existi\u00f3 violencia de g\u00e9nero\u201d.<\/p>\n<p>\u00abPresten atenci\u00f3n a todo el v\u00ednculo de esta pareja, c\u00f3mo lo fue antes y durante el transcurso de este hecho\u201d, dijo el fiscal, quien agreg\u00f3 que convocar\u00e1 como testigos a amigos y familiares de Natal\u00ed Rodr\u00edguez que son las personas \u201cen las cuales ella confiaba y les dec\u00eda qu\u00e9 estaba pasando en esta relaci\u00f3n\u201d.<\/p>\n<p>\u201cYo les voy a pedir atenci\u00f3n a estos testimonios porque les van a demostrar que realmente existi\u00f3 violencia de g\u00e9nero previo a este hecho\u201d resalt\u00f3 el fiscal Viego.<\/p>\n<p>Seguidamente, la abogada Viviana Lozano, representante de los familiares de la v\u00edctima, tambi\u00e9n expres\u00f3 en su alegato: \u201cVamos a intentar reconstruir un hecho a trav\u00e9s de testigos\u201d y, \u201ccomo dijo el fiscal, ac\u00e1 estamos hablando de una cuesti\u00f3n de violencia de g\u00e9nero\u201d.<\/p>\n<p>\u00abUstedes van a ir escuchando distintas situaciones que se produjeron durante el matrimonio, despu\u00e9s del matrimonio y cuando se produjo este homicidio, y van a poder concluir si estos eran hechos de violencia de g\u00e9nero o no\u00bb, concluy\u00f3 la abogada.<\/p>\n<p>A continuaci\u00f3n tuvo lugar el alegato de la defensa del acusado, a cargo del abogado Valent\u00edn Fern\u00e1ndez, quien dijo: \u201cLo que la defensa va a solicitar es que comprendan que no debemos hablar livianamente de violencia de g\u00e9nero porque no qued\u00f3 demostrado que hubo un escenario de ese tipo\u201d.<\/p>\n<p>Adem\u00e1s, el defensor adelant\u00f3 que intentar\u00e1n ilustrar la hip\u00f3tesis de que Calvo actu\u00f3 bajo \u201cun estado de emoci\u00f3n violenta\u201d, y agreg\u00f3: \u201cEs indistinto que haya habido alguna circunstancia de violencia de g\u00e9nero, si Sebasti\u00e1n actu\u00f3 bajo un estado de emoci\u00f3n violenta\u201d.<\/p>\n<p>Despu\u00e9s de los alegatos declar\u00f3 el padre de la v\u00edctima, Ra\u00fal Rodr\u00edguez, quien al ser interrogado por el fiscal y la abogada, relat\u00f3 algunos hechos en los que Calvo hab\u00eda sido protagonista, entre ellos, un presunto intent\u00f3 de suicidio en el patio de la casa de Natal\u00ed.<\/p>\n<p>A su vez, el hombre cont\u00f3 que al acusado lo hab\u00edan visto abriendo el capot del autom\u00f3vil de la v\u00edctima y, tras ello, el veh\u00edculo comenz\u00f3 a presentar inconvenientes mec\u00e1nicos, aunque el testigo afirm\u00f3 que no pod\u00eda precisar cu\u00e1les fueron las razones por las que el veh\u00edculo dej\u00f3 de funcionar.<\/p>\n<p>\u201cEl 15 de marzo del 2022 me mataron a mi hija, me mataron a m\u00ed y a mi se\u00f1ora. Pido justicia, nada m\u00e1s que eso\u201d, finaliz\u00f3 Rodr\u00edguez.<\/p>\n<p>Los voceros indicaron que est\u00e1 previsto que el juicio por jurados que comenz\u00f3 hoy se desarrolle hasta el d\u00eda mi\u00e9rcoles, cuando se estima se conocer\u00e1 el veredicto.<\/p>\n<p>El crimen de Rodr\u00edguez se conoci\u00f3 el 15 de marzo de 2022, cuando Calvo se present\u00f3 espont\u00e1neamente en la subcomisar\u00eda de la localidad de Oriente, ubicada a unos 85 kil\u00f3metros de Coronel Dorrego y confes\u00f3 que hab\u00eda estrangulado a su mujer.<\/p>\n<p>Ante esa confesi\u00f3n, el personal se dirigi\u00f3 a la vivienda ubicada en calle Mitre al 400 de la mencionada localidad bonaerense, donde encontr\u00f3 a la mujer con presuntos signos de estrangulamiento.<\/p>\n<p>Seg\u00fan fuentes judiciales, el acusado se neg\u00f3 a declarar luego ante la Justicia cuando fue indagado y, desde entonces, no volvi\u00f3 a explicar qu\u00e9 fue lo que pas\u00f3.<\/p>\n<p>Tras el hallazgo y a pedido de la Justicia, Calvo qued\u00f3 detenido y, en estos momentos, permanece alojado en la Unidad Penitenciaria 4 de Bah\u00eda Blanca.<\/p>\n<p>(L\u00ednea 144: atenci\u00f3n, contenci\u00f3n y asesoramiento en situaciones de violencia de g\u00e9nero. Por WhatsApp: +5491127716463).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal del juicio por jurados que comenz\u00f3 hoy por el crimen de Natal\u00ed Rodr\u00edguez, hallada estrangulada en marzo del a\u00f1o pasado en su casa del partido bonaerense de Coronel Dorrego, consider\u00f3 hoy que durante la investigaci\u00f3n qued\u00f3 probada la autor\u00eda del asesinato por parte del exnovio de la v\u00edctima, y que est\u00e1 convencido que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":81312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-91329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judiciales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal dijo que hubo &quot;violencia de g\u00e9nero&quot; en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal dijo que hubo &quot;violencia de g\u00e9nero&quot; en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El fiscal del juicio por jurados que comenz\u00f3 hoy por el crimen de Natal\u00ed Rodr\u00edguez, hallada estrangulada en marzo del a\u00f1o pasado en su casa del partido bonaerense de Coronel Dorrego, consider\u00f3 hoy que durante la investigaci\u00f3n qued\u00f3 probada la autor\u00eda del asesinato por parte del exnovio de la v\u00edctima, y que est\u00e1 convencido que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-07T20:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/\",\"name\":\"Fiscal dijo que hubo \\\"violencia de g\u00e9nero\\\" en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg\",\"datePublished\":\"2023-08-07T20:54:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal dijo que hubo \u00abviolencia de g\u00e9nero\u00bb en el crimen de una mujer en Coronel Dorrego en 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal dijo que hubo \"violencia de g\u00e9nero\" en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal dijo que hubo \"violencia de g\u00e9nero\" en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos","og_description":"El fiscal del juicio por jurados que comenz\u00f3 hoy por el crimen de Natal\u00ed Rodr\u00edguez, hallada estrangulada en marzo del a\u00f1o pasado en su casa del partido bonaerense de Coronel Dorrego, consider\u00f3 hoy que durante la investigaci\u00f3n qued\u00f3 probada la autor\u00eda del asesinato por parte del exnovio de la v\u00edctima, y que est\u00e1 convencido que [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2023-08-07T20:54:05+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/","name":"Fiscal dijo que hubo \"violencia de g\u00e9nero\" en el crimen de una mujer en Coronel Dorrego en 2022 - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg","datePublished":"2023-08-07T20:54:05+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/12\/tribunales-26-1200x1200-1.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/fiscal-dijo-que-hubo-violencia-de-genero-en-el-crimen-de-una-mujer-en-coronel-dorrego-en-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Fiscal dijo que hubo \u00abviolencia de g\u00e9nero\u00bb en el crimen de una mujer en Coronel Dorrego en 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/91329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=91329"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/91329\/revisions"}],"predecessor-version":[{"id":91330,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/91329\/revisions\/91330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/81312"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=91329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=91329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=91329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}