{"id":88379,"date":"2023-05-25T12:21:52","date_gmt":"2023-05-25T12:21:52","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=88379"},"modified":"2023-05-25T12:21:52","modified_gmt":"2023-05-25T12:21:52","slug":"a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/","title":{"rendered":"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo"},"content":{"rendered":"<p>Con la vicepresidenta Cristina Fern\u00e1ndez de Kirchner como \u00fanica oradora, el Frente de Todos (FdT) realizar\u00e1, hoy a las 16, en Plaza de Mayo, un acto en conmemoraci\u00f3n por el 20\u00b0 aniversario de la asunci\u00f3n presidencial de N\u00e9stor Kirchner, que contar\u00e1 con la participaci\u00f3n de todos los sectores del oficialismo que esperan definiciones electorales de cara las primarias abiertas, simult\u00e1neas y obligatorias (PASO).<!--more--><\/p>\n<p>La convocatoria, en coincidencia con la fecha patria del 25 de Mayo, se llevar\u00e1 a cabo a menos de un mes de la fecha l\u00edmite para la presentaci\u00f3n de listas de precandidatos, prevista para el pr\u00f3ximo 24 de junio.<\/p>\n<p>\u00abEl jueves los espero a todos y todas en la Plaza de Mayo. A 20 a\u00f1os de la asunci\u00f3n de N\u00e9stor Kirchner, imitemos el ejemplo\u00bb, public\u00f3 el pasado lunes en sus redes sociales Cristina Fern\u00e1ndez de Kirchner para convocar a participar del acto que tiene connotaciones electorales, ya que la propia vicepresidenta gener\u00f3 las expectativas en la entrevista del jueves \u00faltimo en el programa &#8216;Duro de Domar&#8217; que se emite por el canal de noticias C5N.<\/p>\n<p>Al ser consultada sobre cu\u00e1l ser\u00eda su respuesta frente al canto &#8216;Cristina Presidenta&#8217;, la Vicepresidenta respondi\u00f3: \u00abVayan a la Plaza. Hay que ir a la Plaza a escuchar\u00bb, remarc\u00f3.<\/p>\n<p>As\u00ed, todos los sectores dentro del FdT esperan las palabras de la ex presidenta y participar\u00e1n espacios que no se hab\u00edan sumado al operativo clamor por la candidatura de Cristina Kirchner, como el Frente Renovador (FR) y el Movimiento Evita.<\/p>\n<p>Tambi\u00e9n el presidente Alberto Fern\u00e1ndez convoc\u00f3 a la Plaza: \u00abEl 25\/5\/2003 cambi\u00f3 la historia. La llegada de N\u00e9stor Kirchner inici\u00f3 un camino de reparaci\u00f3n moral, justicia social y derechos humanos. Al cumplirse 20 a\u00f1os, convoco a todas y todos a homenajearlo en Plaza de Mayo y escuchar a su compa\u00f1era de vida Cristina Kirchner. N\u00e9stor nos une\u00bb, escribi\u00f3 en su cuenta de Twitter.<\/p>\n<p>En un evento que se espera que sea multitudinario, la expresidenta envi\u00f3 300 invitaciones especiales en la que se destacaron gobernadores, legisladores, intendentes, referentes de organizaciones pol\u00edticas y sociales y dirigentes de organismos de derechos humanos, seg\u00fan se\u00f1alaron desde el entorno de la dos veces expresidenta.<\/p>\n<p>A la espera de su discurso, estipulado para las 16, las distintas organizaciones pol\u00edticas, sociales y sindicales convocaron al mediod\u00eda en la zona del microcentro mientras que La C\u00e1mpora convoc\u00f3 a reunirse en Plaza de Mayo a las 14.<\/p>\n<p>Por eso, la zona de Plaza de Mayo y las cuadras aleda\u00f1as se ver\u00e1n afectadas su normal circulaci\u00f3n desde pasado el mediod\u00eda.<\/p>\n<p>Con respecto al armado del acto, desde ayer al mediod\u00eda comenz\u00f3 el despliegue de estructuras y de operarios que aceleraron el pulso de los trabajos para montar un escenario ubicado en la Plaza de Mayo, entre la Pir\u00e1mide de Mayo y el Monumento a Manuel Belgrano, de espaldas a la Casa de Gobierno.<\/p>\n<p>La tribuna desde d\u00f3nde dirigir\u00e1 la palabra la Vicepresidenta se eleva cerca de 3 metros del suelo y tiene un frente de m\u00e1s de 15 metros de largo, coronada por dos pantallas gigantes a cada uno de los lados.<\/p>\n<p>Ante el pron\u00f3stico de un clima lluvioso para hoy en la ciudad de Buenos Aires, el escenario cuenta con un techo que se mont\u00f3 a m\u00e1s de 20 metros de altura y en el per\u00edmetro del escenario se colocaron las vallas de seguridad, formando un anillo de 30 metros de di\u00e1metro, d\u00f3nde s\u00f3lo acceder\u00e1n los organizadores y los invitados especiales.<\/p>\n<p>Adem\u00e1s se montaron equipos electr\u00f3genos, camerinos y dos carpas de m\u00e1s de 25 metros de largo para recibir a los invitados cerca de la intersecci\u00f3n de Balcarce e Hip\u00f3lito Yrigoyen.<\/p>\n<p>Mientras tanto, en el otro extremo de la Plaza, se montaron tres pantallas y torres de sonido que apuntan, cada una a la Avenida de Mayo, a la Diagonal Julio A. Roca y a la Diagonal Roque S\u00e1enz Pe\u00f1a.<\/p>\n<p>Para avanzar en la organizaci\u00f3n del acto, la Vicepresidenta y el presidente del PJ bonaerense y diputado nacional, M\u00e1ximo Kirchner, se reunieron con referentes del Movimiento Evita para \u00abultimar detalles\u00bb.<\/p>\n<p>As\u00ed lo cont\u00f3 la cuenta oficial del Movimiento Evita, que tambi\u00e9n expres\u00f3: \u00abSeguimos trabajando para fortalecer la unidad del campo nacional y popular\u00bb.<\/p>\n<p>En declaraciones radiales, el referente del Movimiento Evita y secretario Econom\u00eda Social, Emilio P\u00e9rsico, afirm\u00f3: \u00abCreemos que tendr\u00edamos que tener mucha movilizaci\u00f3n popular y que hay que construir un espacio de unidad en la calle muy grande. Va a haber much\u00edsima gente\u00bb, estim\u00f3.<\/p>\n<p>A su turno, el jefe de Gabinete, Agust\u00edn Rossi, consider\u00f3 que \u00abva a ser un d\u00eda festivo a pesar de que N\u00e9stor no est\u00e1 entre nosotros\u00bb y que \u00abtodos los sectores van a estar representados\u00bb en la Plaza.<\/p>\n<p>Con el mismo objetivo, el ministro del Interior, Eduardo &#8216;Wado&#8217; de Pedro y el diputado nacional y presidente del PJ bonaerense, M\u00e1ximo Kirchner, se reunieron en Quilmes el pasado lunes con intendentes del conurbano bonaerense y dirigentes del peronismo provincial.<\/p>\n<p>Luego, M\u00e1ximo Kirchner mantuvo un encuentro en el despacho de la presidenta de la C\u00e1mara de Diputados, Cecilia Moreau, con la mesa ejecutiva del FR, en la cual se acord\u00f3 que ese espacio liderado por el ministro de Econom\u00eda, Sergio Massa, participe del acto de hoy.<\/p>\n<p>Por su parte, De Pedro se reuni\u00f3 con el diputado y l\u00edder de la CTA, Hugo Yasky, en la sede porte\u00f1a, donde consider\u00f3 que la movilizaci\u00f3n buscar\u00e1 tambi\u00e9n \u00abdecir basta a sectores del Poder Judicial que no est\u00e1n investigando sobre los responsables intelectuales y materiales del intento de asesinato de Cristina\u00bb.<\/p>\n<p>Yasky dijo que el acto \u00abtendr\u00e1 un car\u00e1cter hist\u00f3rico, de esos que quedar\u00e1n grabados en la memoria popular. Vamos a conmemorar los 20 a\u00f1os de la asunci\u00f3n de N\u00e9stor (Kirchner) y habr\u00e1 una multitud que seguramente todav\u00eda tiene esperanza en que Cristina encauce esta historia\u00bb.<\/p>\n<p>La idea de realizar un acto en conmemoraci\u00f3n de los 20 a\u00f1os de la asunci\u00f3n de N\u00e9stor Kirchner surgi\u00f3 del grupo de sindicatos afines al kirchnerismo que se lo propusieron a la Vicepresidenta en una reuni\u00f3n el pasado 12 de abril en su despacho del Senado.<\/p>\n<p>A pesar de que esa convocatoria formaba parte del operativo clamor para que Cristina Kirchner acepte ser candidata a Presidenta, la realizaci\u00f3n del acto se mantuvo tras la ratificaci\u00f3n de la vicepresidenta de que no ser\u00e1 candidata, aunque se cambi\u00f3 el lugar que pas\u00f3 de la avenida 9 de julio a la Plaza de Mayo.<\/p>\n<p>Semanas atr\u00e1s se sumaron a la organizaci\u00f3n los sectores que conforman &#8216;La Mesa de Ensenada&#8217;, que fueron los encargados del armado de los plenarios de la militancia que bregan por vencer a la proscripci\u00f3n de la vicepresidenta producto de la condena en primera instancia por el caso &#8216;Vialidad&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la vicepresidenta Cristina Fern\u00e1ndez de Kirchner como \u00fanica oradora, el Frente de Todos (FdT) realizar\u00e1, hoy a las 16, en Plaza de Mayo, un acto en conmemoraci\u00f3n por el 20\u00b0 aniversario de la asunci\u00f3n presidencial de N\u00e9stor Kirchner, que contar\u00e1 con la participaci\u00f3n de todos los sectores del oficialismo que esperan definiciones electorales de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-88379","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Con la vicepresidenta Cristina Fern\u00e1ndez de Kirchner como \u00fanica oradora, el Frente de Todos (FdT) realizar\u00e1, hoy a las 16, en Plaza de Mayo, un acto en conmemoraci\u00f3n por el 20\u00b0 aniversario de la asunci\u00f3n presidencial de N\u00e9stor Kirchner, que contar\u00e1 con la participaci\u00f3n de todos los sectores del oficialismo que esperan definiciones electorales de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-25T12:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/\",\"name\":\"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2023-05-25T12:21:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos","og_description":"Con la vicepresidenta Cristina Fern\u00e1ndez de Kirchner como \u00fanica oradora, el Frente de Todos (FdT) realizar\u00e1, hoy a las 16, en Plaza de Mayo, un acto en conmemoraci\u00f3n por el 20\u00b0 aniversario de la asunci\u00f3n presidencial de N\u00e9stor Kirchner, que contar\u00e1 con la participaci\u00f3n de todos los sectores del oficialismo que esperan definiciones electorales de [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2023-05-25T12:21:52+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/","name":"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2023-05-25T12:21:52+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/a-menos-de-un-mes-del-cierre-de-listas-cristina-kirchner-encabeza-un-acto-en-plaza-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"A menos de un mes del cierre de listas, Cristina Kirchner encabeza un acto en Plaza de Mayo"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=88379"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88379\/revisions"}],"predecessor-version":[{"id":88381,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88379\/revisions\/88381"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=88379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=88379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=88379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}