{"id":88106,"date":"2023-05-18T11:47:58","date_gmt":"2023-05-18T11:47:58","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=88106"},"modified":"2023-05-18T11:47:58","modified_gmt":"2023-05-18T11:47:58","slug":"luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/","title":{"rendered":"Luis Castro reclama a Bordoni por el bacheo de la ruta 76"},"content":{"rendered":"<p>El concejal de Juntos envi\u00f3 una nota al intendente de Tornquist para que interceda en Vialidad de la Provincia para que se realice un bacheo previo al finde largo del 25 de mayo.<!--more--><\/p>\n<p><a data-flickr-embed=\"true\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/52906158892\/in\/dateposted-public\/\" title=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/52906158892_c49f417529_z.jpg\" width=\"360\" height=\"640\" alt=\"image\"\/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concejal de Juntos envi\u00f3 una nota al intendente de Tornquist para que interceda en Vialidad de la Provincia para que se realice un bacheo previo al finde largo del 25 de mayo.<\/p>\n","protected":false},"author":3,"featured_media":74596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-88106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El concejal de Juntos envi\u00f3 una nota al intendente de Tornquist para que interceda en Vialidad de la Provincia para que se realice un bacheo previo al finde largo del 25 de mayo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T11:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/\",\"name\":\"Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg\",\"datePublished\":\"2023-05-18T11:47:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg\",\"width\":848,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luis Castro reclama a Bordoni por el bacheo de la ruta 76\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/","og_locale":"es_ES","og_type":"article","og_title":"Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos","og_description":"El concejal de Juntos envi\u00f3 una nota al intendente de Tornquist para que interceda en Vialidad de la Provincia para que se realice un bacheo previo al finde largo del 25 de mayo.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2023-05-18T11:47:58+00:00","og_image":[{"width":848,"height":477,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/","name":"Luis Castro reclama a Bordoni por el bacheo de la ruta 76 - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg","datePublished":"2023-05-18T11:47:58+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/07\/ruta-76-abra.jpg","width":848,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/luis-castro-reclama-a-bordoni-por-el-bacheo-de-la-ruta-76\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Luis Castro reclama a Bordoni por el bacheo de la ruta 76"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=88106"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88106\/revisions"}],"predecessor-version":[{"id":88107,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/88106\/revisions\/88107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/74596"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=88106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=88106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=88106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}