{"id":8460,"date":"2017-03-28T13:02:39","date_gmt":"2017-03-28T16:02:39","guid":{"rendered":"http:\/\/noticiasradioreflejos.com.ar\/noticias\/?p=8460"},"modified":"2017-03-28T13:02:39","modified_gmt":"2017-03-28T16:02:39","slug":"el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/","title":{"rendered":"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente"},"content":{"rendered":"<p lang=\"es-ES\" style=\"text-align: left;\" align=\"center\"><b><\/b><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">La Seccional Buenos Aires del SADOP pone de manifiesto p\u00fablicamente su TOTAL RECHAZO a la Comunicaci\u00f3n 53 de la DIPREGEP (Direcci\u00f3n Provincial de Educaci\u00f3n de Gesti\u00f3n Privada).<\/span><\/span><!--more--><\/p>\n<p lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Con fecha 23 de Marzo del corriente la Jueza Mar\u00eda Ventura Mart\u00ednez, titular del Juzgado Contencioso Administrativo Nro 2 de la Ciudad de La Plata, dispuso por Resoluci\u00f3n Judicial, en autos. \u201c FEDERACION DE EDUCADORES BONAERENSES Y OTRO\/A C\/PODER EJECUTIVO S\/PRETENSION ANULATORIA\u201d y del cual SADOP es parte, que la Direcci\u00f3n General de Cultura y Educaci\u00f3n se abstenga de practicar descuentos por huelga y\/o gratificar a quien no haga los paros\u201d.<\/span><\/span><\/p>\n<p lang=\"es-ES\" align=\"justify\">\u201c<span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Dichas acciones analizadas en conjunto poseen virtualidad suficiente para incidir en el esp\u00edritu del trabajador a la hora de tomar la decisi\u00f3n de realizar huelga\u201d&#8230; y porque \u201c no s\u00f3lo al operar as\u00ed sobre la voluntad (conf.art.276 CCyC) del trabajador, afectan su libertad, sino, tangencialmente, resultan atentatorias del derecho de huelga (art.39 CP)\u201d e \u201cimplican actos que alteran, restringen, limitan o afectan, la libertad de los trabajadores y sus entidades gremiales en las negociaciones colectivas\u201d.<\/span><\/span><\/p>\n<p lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">P<\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\">or lo expuesto el <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><b>SADOP INTIM\u00d3 mediante Carta Documento a la DIPREGEP se abstenga<\/b><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"> de cualquier tipo de acci\u00f3n o procedimiento que pueda violentar la manda Judicial.<\/span><\/span><\/p>\n<p lang=\"es-ES\" style=\"text-align: left;\" align=\"center\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><b>EN DEFENSA DE NUESTROS DERECHOS LABORALES Y POR CONDICIONES DIGNAS DE TRABAJO.<\/b><\/span><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Seccional Buenos Aires del SADOP pone de manifiesto p\u00fablicamente su TOTAL RECHAZO a la Comunicaci\u00f3n 53 de la DIPREGEP (Direcci\u00f3n Provincial de Educaci\u00f3n de Gesti\u00f3n Privada).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-8460","post","type-post","status-publish","format-standard","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Seccional Buenos Aires del SADOP pone de manifiesto p\u00fablicamente su TOTAL RECHAZO a la Comunicaci\u00f3n 53 de la DIPREGEP (Direcci\u00f3n Provincial de Educaci\u00f3n de Gesti\u00f3n Privada).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-28T16:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/\",\"name\":\"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2017-03-28T16:02:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/","og_locale":"es_ES","og_type":"article","og_title":"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos","og_description":"La Seccional Buenos Aires del SADOP pone de manifiesto p\u00fablicamente su TOTAL RECHAZO a la Comunicaci\u00f3n 53 de la DIPREGEP (Direcci\u00f3n Provincial de Educaci\u00f3n de Gesti\u00f3n Privada).","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2017-03-28T16:02:39+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/","name":"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2017-03-28T16:02:39+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-sadop-rechaza-la-comunicacion-nro-53-de-la-dipregep-y-exige-que-se-cumpla-con-fallo-judicial-vigente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El SADOP Rechaza la comunicaci\u00f3n Nro. 53 de la DIPREGEP y exig\u00e9 que se cumpla con fallo judicial vigente"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/8460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=8460"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/8460\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=8460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=8460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=8460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}