{"id":82887,"date":"2023-01-19T18:38:25","date_gmt":"2023-01-19T18:38:25","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=82887"},"modified":"2023-01-19T18:38:25","modified_gmt":"2023-01-19T18:38:25","slug":"jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/","title":{"rendered":"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d"},"content":{"rendered":"<p>El referente de la UCR local sali\u00f3 al cruce de los dichos del intendente en el acto por el aniversario de Sierra de la Ventana. Al mismo tiempo asegur\u00f3 que \u201cla UCR est\u00e1 en una posici\u00f3n favorable\u201d de cara a las pr\u00f3ximas elecciones.<!--more--><\/p>\n<p>El discurso del jefe comunal sigue dando de qu\u00e9 hablar. En esta ocasi\u00f3n quien sali\u00f3 al cruce fue el presidente de la UCR Tornquist, Manuel Castro, el cual se mostr\u00f3 disconforme con lo dicho por Sergio Bordoni.<\/p>\n<p>Al respecto afirm\u00f3 que \u201cestuve en el acto. Presenci\u00e9 y escuch\u00e9 el discurso del intendente. Creo que no fue afortunado ni era el momento. En el aniversario de un pueblo, los que asistimos y m\u00e1s de los que no somos de esa localidad, justamente tenemos que acompa\u00f1ar al vecino del pueblo y a sus instituciones, con un mensaje esperanzador\u201d.<\/p>\n<p>En esa l\u00ednea asegur\u00f3 que \u201cel intendente se har\u00e1 cargo de lo que dijo. Tendr\u00e1 en cierta parte raz\u00f3n o no, pero es cierto que lo que se dio en Sierra se da en otras localidades, aunque haya ciudades con m\u00e1s sentido de pertenencia\u201d.<\/p>\n<p>Aunque cerrando la idea mencion\u00f3 que \u201cen lo que s\u00ed coincido es que hay que estar unidos, tirar todos para el mismo lado y acompa\u00f1ar a las instituciones\u201d.<\/p>\n<h3>La UCR en la provincia<\/h3>\n<p>En otro pasaje de la charla Castro confirm\u00f3 que \u201cMaximiliano Abad ma\u00f1ana en Mar del Plata har\u00e1 el acto de lanzamiento de su candidatura. Posiblemente haya otro candidato como Gustavo Posse. Son posibles candidatos a la gobernaci\u00f3n provincial e ir\u00e1n a las PASO\u201d.<\/p>\n<p>A su modo de ver \u201cla interna es sana, y tambi\u00e9n existe la posibilidad que se integre una lista cruzada, con gobernador del UCR o Pro, y un vice del otro partido. A\u00fan no hay nada en concreto. A partir de marzo habr\u00e1 definiciones m\u00e1s concretas\u201d.<\/p>\n<p>Seg\u00fan su visi\u00f3n \u201cla UCR est\u00e1 en una posici\u00f3n favorable, sobre todo en el interior, y eso le da espalda y \u00e1nimo para competir en una PASO con un candidato del PRO\u201d.<\/p>\n<h3>Sobre sus estudios de autonom\u00eda<\/h3>\n<p>De la mano con lo dicho por Bordoni, y el supuesto entre l\u00edneas que dej\u00f3 correr en donde le abre la puerta a Sierra de la Ventana para que se independice, Castro afirm\u00f3 que \u201ctodav\u00eda no he tomado una postura definida al respecto. Por ahora tengo una visi\u00f3n amplia de por qu\u00e9 no es la primera vez que se plantea la posibilidad de autonom\u00eda\u201d.<\/p>\n<p>Esto pese a que \u201cen 2020 cuando terminaba mi profesorado de historia hice un trabajo relacionado a lo hist\u00f3rico y social. Tom\u00e9 este tema, que siempre se habl\u00f3 en el pueblo, y en el cual me ayudaron muchos vecinos. Hay mucho de imaginario popular. Lo que s\u00ed se sabe que el 80% es de coparticipaci\u00f3n y el 20% restante es por tasas\u201d.<\/p>\n<p><iframe loading=\"lazy\" width=\"100%\" height=\"166\" scrolling=\"no\" frameborder=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1427827162&#038;color=%23ff5500&#038;auto_play=false&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false&#038;show_teaser=true\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc;line-break: anywhere;word-break: normal;overflow: hidden;white-space: nowrap;text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif;font-weight: 100;\"><a href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\" title=\"fmreflejos 103.7\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">fmreflejos 103.7<\/a> \u00b7 <a href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\/manuel-castro-4\" title=\"Manuel Castro\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">Manuel Castro<\/a><\/div>\n<p  style=\" margin: 12px auto 6px auto; font-family: Helvetica,Arial,Sans-serif; font-style: normal; font-variant: normal; font-weight: normal; font-size: 14px; line-height: normal; font-size-adjust: none; font-stretch: normal; -x-system-font: none; display: block;\">   <a title=\"View Imaginarios de La Autonomia 2020.Docx on Scribd\" href=\"https:\/\/www.scribd.com\/document\/620763622\/Imaginarios-de-La-Autonomia-2020-Docx#from_embed\"  style=\"text-decoration: underline;\" >Imaginarios de La Autonomia 2020.Docx<\/a> by <a title=\"View FM Reflejos Sierra de la Ventana's profile on Scribd\" href=\"https:\/\/es.scribd.com\/user\/128459674\/FM-Reflejos-Sierra-de-la-Ventana#from_embed\"  style=\"text-decoration: underline;\" >FM Reflejos Sierra de la Ventana<\/a> on Scribd<\/p>\n<p><iframe loading=\"lazy\" class=\"scribd_iframe_embed\" title=\"Imaginarios de La Autonomia 2020.Docx\" src=\"https:\/\/es.scribd.com\/embeds\/620763622\/content?start_page=1&#038;view_mode=scroll&#038;access_key=key-zvoEazJQFo9MuJTDk0gz\" data-auto-height=\"true\" data-aspect-ratio=\"0.7080062794348508\" scrolling=\"no\" id=\"doc_12159\" width=\"100%\" height=\"600\" frameborder=\"0\"><\/iframe><script type=\"text\/javascript\">(function() { var scribd = document.createElement(\"script\"); scribd.type = \"text\/javascript\"; scribd.async = true; scribd.src = \"https:\/\/es.scribd.com\/javascripts\/embed_code\/inject.js\"; var s = document.getElementsByTagName(\"script\")[0]; s.parentNode.insertBefore(scribd, s); })();<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El referente de la UCR local sali\u00f3 al cruce de los dichos del intendente en el acto por el aniversario de Sierra de la Ventana. Al mismo tiempo asegur\u00f3 que \u201cla UCR est\u00e1 en una posici\u00f3n favorable\u201d de cara a las pr\u00f3ximas elecciones.<\/p>\n","protected":false},"author":3,"featured_media":82891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-82887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El referente de la UCR local sali\u00f3 al cruce de los dichos del intendente en el acto por el aniversario de Sierra de la Ventana. Al mismo tiempo asegur\u00f3 que \u201cla UCR est\u00e1 en una posici\u00f3n favorable\u201d de cara a las pr\u00f3ximas elecciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T18:38:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2304\" \/>\n\t<meta property=\"og:image:height\" content=\"1296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/\",\"name\":\"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg\",\"datePublished\":\"2023-01-19T18:38:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg\",\"width\":2304,\"height\":1296},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos","og_description":"El referente de la UCR local sali\u00f3 al cruce de los dichos del intendente en el acto por el aniversario de Sierra de la Ventana. Al mismo tiempo asegur\u00f3 que \u201cla UCR est\u00e1 en una posici\u00f3n favorable\u201d de cara a las pr\u00f3ximas elecciones.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2023-01-19T18:38:25+00:00","og_image":[{"width":2304,"height":1296,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/","name":"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg","datePublished":"2023-01-19T18:38:25+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2023\/01\/Aniversario115-SDLV-11.jpg","width":2304,"height":1296},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/jose-manuel-castro-el-intendente-se-hara-cargo-de-lo-que-dijo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Manuel Castro: \u201cEl intendente se har\u00e1 cargo de lo que dijo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/82887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=82887"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/82887\/revisions"}],"predecessor-version":[{"id":82892,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/82887\/revisions\/82892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/82891"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=82887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=82887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=82887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}