{"id":66948,"date":"2022-01-11T22:00:12","date_gmt":"2022-01-11T22:00:12","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=66948"},"modified":"2022-01-11T22:00:12","modified_gmt":"2022-01-11T22:00:12","slug":"al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/","title":{"rendered":"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76"},"content":{"rendered":"<p>Hace unas semanas pudimos ser testigos de una obra de bacheo sobre la ruta 76 entre San Eloy y la Ruta nacional 33, que el 20 de diciembre de 2021 fue anunciada por algunos referentes del Frente de TODXS Tornquist como un alivio para la seguridad de los turistas. <!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66950\" src=\"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/01\/no-son-pocos.jpeg\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p>Realmente como cuatro ojos ven mejor que dos, nosotros recorrimos la ruta y como muestran las im\u00e1genes la obra realizada en diciembre dejaba mucho que desear en cuanto a calidad de la obra y sobre todo porque se hab\u00edan olvidado 37 pozos.<\/p>\n<p>Nosotros que junto a asociaciones vecinales y comerciantes venimos bregando hace mucho tiempo para que la ruta se realice definitivamente hicimos gestiones para que el error de ponderar positivamente una obra mal realizada se pueda corregir a la brevedad sobre todo haciendo llegar el descontento de los vecinos por la obra mal realizada en el mes de diciembre pasado y confiando en la palabra de nuestro gobernador Axel Kicillof de realizar la repavimentaci\u00f3n definitiva sobre la ruta 76 a partir del a\u00f1o 2022.<\/p>\n<p>Este compromiso del gobernador se hab\u00eda concretado en Coronel Suarez en 2019 cuando le entregamos una carpeta con el estado de la ruta, y fue confirmado ante la prensa en enero del 2021 durante su visita a Sierra de la Ventana.<\/p>\n<p>La semana pasada recibimos la confirmaci\u00f3n que se comenzar\u00eda la intervenci\u00f3n sobre la ruta 76 en tramos y que pronto \u00edbamos a tener verdaderas buenas noticias.<\/p>\n<p>Hoy compartimos con la comunidad la alegr\u00eda de ver que junto al intendente de Coronel Suarez Ricardo Mocero se realiz\u00f3 el acto de apertura de sobres para repavimentar los primeros 38 kil\u00f3metros entre el l\u00edmite del partido de General Lamadrid y el arroyo El Perdido y que se incluir\u00e1 la rotonda de intersecci\u00f3n de las rutas provinciales N\u00b0 85 y N\u00b0 76. De \u00e9sta forma entonces se da comienzo a lo que ser\u00e1 la obra definitiva sobre toda la traza de la ruta provincial 76.<\/p>\n<p>Como siempre nos seguiremos poniendo a disposici\u00f3n para que cada d\u00eda nuestra gobernanza sea mejor, para que se cumpla la palabra de nuestras autoridades, y sobre todo que las pol\u00edticas p\u00fablicas se desarrollen entre TODXS y con el compromiso que le prometimos a los electores.<\/p>\n<p>PARTIDO FRENTE GRANDE<\/p>\n<p style=\"text-align: left;\">Claudio Masson<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unas semanas pudimos ser testigos de una obra de bacheo sobre la ruta 76 entre San Eloy y la Ruta nacional 33, que el 20 de diciembre de 2021 fue anunciada por algunos referentes del Frente de TODXS Tornquist como un alivio para la seguridad de los turistas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-66948","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Hace unas semanas pudimos ser testigos de una obra de bacheo sobre la ruta 76 entre San Eloy y la Ruta nacional 33, que el 20 de diciembre de 2021 fue anunciada por algunos referentes del Frente de TODXS Tornquist como un alivio para la seguridad de los turistas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T22:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/01\/no-son-pocos.jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/\",\"name\":\"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/01\/no-son-pocos.jpeg\",\"datePublished\":\"2022-01-11T22:00:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/","og_locale":"es_ES","og_type":"article","og_title":"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos","og_description":"Hace unas semanas pudimos ser testigos de una obra de bacheo sobre la ruta 76 entre San Eloy y la Ruta nacional 33, que el 20 de diciembre de 2021 fue anunciada por algunos referentes del Frente de TODXS Tornquist como un alivio para la seguridad de los turistas.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2022-01-11T22:00:12+00:00","og_image":[{"url":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/01\/no-son-pocos.jpeg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/","name":"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76 - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage"},"thumbnailUrl":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/01\/no-son-pocos.jpeg","datePublished":"2022-01-11T22:00:12+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/al-fin-comienza-la-obra-de-repavimentacion-de-la-ruta-76\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Al fin comienza la obra de repavimentaci\u00f3n de la ruta 76"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=66948"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66948\/revisions"}],"predecessor-version":[{"id":66951,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66948\/revisions\/66951"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=66948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=66948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=66948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}