{"id":66917,"date":"2022-01-11T12:40:28","date_gmt":"2022-01-11T12:40:28","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=66917"},"modified":"2022-01-11T12:40:28","modified_gmt":"2022-01-11T12:40:28","slug":"hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/","title":{"rendered":"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles"},"content":{"rendered":"<p>La Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, informa que hasta el viernes 14 de enero se encuentra abierta la inscripci\u00f3n a becas y residencias estudiantiles para el presente a\u00f1o.<!--more--><\/p>\n<p>Los interesados, deben descargar el siguiente formulario: <a href=\"https:\/\/drive.google.com\/drive\/u\/0\/folders\/1pu41HwYN8CUb6wcfrC2D-8MZCUGGUcQS\">https:\/\/drive.google.com\/drive\/u\/0\/folders\/1pu41HwYN8CUb6wcfrC2D-8MZCUGGUcQS<\/a>. Una vez completado, presentarlo en las oficinas de Ventura Picado 111 (Tornquist), o por mail a <a href=\"mailto:juventud.tornquist@gmail.com\">juventud.tornquist@gmail.com<\/a>.<\/p>\n<p>Por consultas, comunicarse por Whatsapp al 2915365453.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, informa que hasta el viernes 14 de enero se encuentra abierta la inscripci\u00f3n a becas y residencias estudiantiles para el presente a\u00f1o.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-66917","post","type-post","status-publish","format-standard","hentry","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, informa que hasta el viernes 14 de enero se encuentra abierta la inscripci\u00f3n a becas y residencias estudiantiles para el presente a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T12:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/\",\"name\":\"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2022-01-11T12:40:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/","og_locale":"es_ES","og_type":"article","og_title":"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos","og_description":"La Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, informa que hasta el viernes 14 de enero se encuentra abierta la inscripci\u00f3n a becas y residencias estudiantiles para el presente a\u00f1o.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2022-01-11T12:40:28+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/","name":"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2022-01-11T12:40:28+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hasta-el-viernes-14-esta-abierta-la-inscripcion-a-becas-y-residencias-estudiantiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Hasta el viernes 14 est\u00e1 abierta la inscripci\u00f3n a becas y residencias estudiantiles"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=66917"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66917\/revisions"}],"predecessor-version":[{"id":66918,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66917\/revisions\/66918"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=66917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=66917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=66917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}