{"id":66768,"date":"2022-01-07T11:26:57","date_gmt":"2022-01-07T11:26:57","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=66768"},"modified":"2022-01-07T11:26:57","modified_gmt":"2022-01-07T11:26:57","slug":"corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/","title":{"rendered":"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas"},"content":{"rendered":"<p>COOPERSIVE LTDA Informa a la poblaci\u00f3n que el corte sufrido por nuestro servicio de Internet en la noche de ayer, y que se manifestara entre las 22 y las 24 horas, se ocasion\u00f3 en un problema que registr\u00f3 uno de los proveedores del servicio.<!--more--><\/p>\n<p>Luego de esa hora, nuestros t\u00e9cnicos reestablecieron la prestaci\u00f3n del mismo, sin registrar con posterioridad inconvenientes.<\/p>\n<p>Sepan disculpar las molestias ocasionadas.<\/p>\n<h4><\/h4>\n<h4>Consejo de Administraci\u00f3n<\/h4>\n<h4>07-ene-2022<\/h4>\n<h4><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>COOPERSIVE LTDA Informa a la poblaci\u00f3n que el corte sufrido por nuestro servicio de Internet en la noche de ayer, y que se manifestara entre las 22 y las 24 horas, se ocasion\u00f3 en un problema que registr\u00f3 uno de los proveedores del servicio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-66768","post","type-post","status-publish","format-standard","hentry","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"COOPERSIVE LTDA Informa a la poblaci\u00f3n que el corte sufrido por nuestro servicio de Internet en la noche de ayer, y que se manifestara entre las 22 y las 24 horas, se ocasion\u00f3 en un problema que registr\u00f3 uno de los proveedores del servicio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T11:26:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/\",\"name\":\"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2022-01-07T11:26:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/","og_locale":"es_ES","og_type":"article","og_title":"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos","og_description":"COOPERSIVE LTDA Informa a la poblaci\u00f3n que el corte sufrido por nuestro servicio de Internet en la noche de ayer, y que se manifestara entre las 22 y las 24 horas, se ocasion\u00f3 en un problema que registr\u00f3 uno de los proveedores del servicio.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2022-01-07T11:26:57+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/","name":"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2022-01-07T11:26:57+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/corte-servicio-internet-producido-el-jueves-06-ene-2022-de-22-a-24-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Corte servicio internet producido el jueves 06-ene-2022 de 22 a 24 horas"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=66768"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66768\/revisions"}],"predecessor-version":[{"id":66769,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/66768\/revisions\/66769"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=66768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=66768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=66768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}