{"id":65038,"date":"2021-11-17T19:52:51","date_gmt":"2021-11-17T19:52:51","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=65038"},"modified":"2021-11-17T19:52:51","modified_gmt":"2021-11-17T19:52:51","slug":"advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/","title":{"rendered":"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \u00abcara grande\u00bb"},"content":{"rendered":"<p>El fiscal<strong> Horacio Azzolin<\/strong>, titular de la Unidad Fiscal Especializada en Ciberdelincuencia (UFECI), alert\u00f3 a trav\u00e9s de su cuenta de Twitter sobre una nueva modalidad de fraude.\u00a0<!--more--><\/p>\n<figure class=\"mb-3\"><img decoding=\"async\" src=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg\" alt=\"La estafa se realiza a travs de mensajes de Whats App \" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>La estafa se realiza a trav\u00e9s de mensajes de Whats App.<\/figcaption><\/figure>\n<p>Un fiscal especializado en cibercrimen advirti\u00f3 este mi\u00e9rcoles sobre una\u00a0<strong>nueva modalidad de estafa que incluye el robo de una cuenta de WhatsApp<\/strong>\u00a0a partir de la cual los\u00a0<strong>delincuentes acceden a los contactos de la v\u00edctima y les ofrecen como anzuelo venderles d\u00f3lares \u00abcara grande\u00bb a cambio de una transferencia o un dep\u00f3sito bancario.<\/strong><\/p>\n<p>La advertencia fue anunciada por el fiscal Horacio Azzolin, titular de la Unidad Fiscal Especializada en Ciberdelincuencia (UFECI), a trav\u00e9s de su cuenta de Twitter @horacioazzolin.<\/p>\n<p>El fiscal se\u00f1al\u00f3 que desde la UFECI est\u00e1n viendo una serie de\u00a0<strong>\u00abfraudes asociados a usurpaci\u00f3n de identidad, especialmente en Whatsapp\u00bb.<\/strong><\/p>\n<p>En una de las capturas de pantalla publicada por la fiscal\u00eda, se advierte una nueva estafa en la que el ciberdelincuente toma el control de la cuenta de WhatsApp de una persona, tiene todos sus contactos y le manda a familiares o amigos mensajes para ofrecer d\u00f3lares \u00abcara grande\u00bb, es decir de la serie m\u00e1s nueva y en contraposici\u00f3n de los menospreciados \u00abcara chica\u00bb, y a un precio tentador.<\/p>\n<p>\u00abQuerida, vos ten\u00e9s a alguien que pueda comprar d\u00f3lares? Necesito vender 2.500 d\u00f3lares cara grande. Necesito los pesos por transferencia o dep\u00f3sito bancario\u00bb, son algunos de los mensajes de una captura de pantalla aportada por la fiscal\u00eda.<\/p>\n<p>En otra de las im\u00e1genes, se observan dos fotograf\u00edas de diez billetes de 100 d\u00f3lares \u00abazules\u00bb o de \u00abcara grande\u00bb, con el mensaje: \u00abTengo estos $1.000 a 150\u00bb pesos, (la cotizaci\u00f3n es de hace unas semanas).<\/p>\n<p>\u00abDesde hace algunas semanas mucha gente est\u00e1 recibiendo mensajes por WhatsApp de conocidos en los que les piden plata prestada por alg\u00fan problema puntual o les ofrecen comprarles d\u00f3lares a buen precio\u00bb, explica Azzolin en sus tuits.<\/p>\n<p>\u00abQuienes hacen esto consiguen los contactos de la persona cuya identidad toman por diversos medios\u00bb, afirm\u00f3 y all\u00ed advirti\u00f3 sobre falsos mails de cuentas de correos electr\u00f3nico supuestamente desactivadas o con el logo de bancos, pero explic\u00f3 que ahora los estafadores roban cuentas de WhatsApp.<\/p>\n<blockquote class=\"\"><p>\u00abDesde hace algunas semanas mucha gente est\u00e1 recibiendo mensajes por WhatsApp de conocidos en los que les piden plata prestada por alg\u00fan problema puntual o les ofrecen comprarles d\u00f3lares a buen precio\u00bb.<\/p><\/blockquote>\n<p>Uno de los m\u00e9todos, seg\u00fan Azzolin, es que\u00a0<strong>con datos ciertos y hasta con una foto de perfil que puede ser la de la v\u00edctima del robo de la identidad, env\u00edan mensajes a familiares y amigos desde una nueva l\u00ednea telef\u00f3nica,<\/strong>\u00a0con la advertencia de que lo agendes porque cambiaron el n\u00famero y luego piden prestada plata u ofrecen los d\u00f3lares.<\/p>\n<p>\u00abHola ahijado, c\u00f3mo and\u00e1s? Soy \u2026, agend\u00e1\u00bb, dice uno de los mensajes publicados por la fiscal\u00eda y que obtuvo como respuesta: \u00abHola t\u00eda, ya te agendo\u00bb, lo que demuestra que con un par de datos y poco de charla previa, ahora la persona que ser\u00e1 estafada cree que ese conocido cambi\u00f3 su n\u00famero de WhatsApp, cuando en realidad es todo una farsa.<\/p>\n<figure class=\"mb-3\"><img decoding=\"async\" class=\" lazy \" src=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/06\/60d5fce169bb9_900.jpg\" alt=\"Recuerdan no ncompartir los cdigos de verificacin por ningn motivo \" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>Recuerdan no compartir los c\u00f3digos de verificaci\u00f3n por ning\u00fan motivo.<\/figcaption><\/figure>\n<p>\u00abLa otra variante es, en vez de usar un supuesto &#8216;nuevo n\u00famero&#8217;, usar la cuenta de WhatsApp de la v\u00edctima que tomaron previamente\u00bb, se\u00f1al\u00f3 Azzolin para luego dar una serie de consejos para evitar lo que en la jerga se conoce como el \u00abtake over\u00bb de cuentas de la popular aplicaci\u00f3n de mensajer\u00eda.<\/p>\n<p>Lo m\u00e1s importante, seg\u00fan la UFECI, es\u00a0<strong>nunca entregar a nadie y bajo ning\u00fan motivo el c\u00f3digo de verificaci\u00f3n que la plataforma WhatsApp env\u00eda por mensaje de texto (SMS).<\/strong><\/p>\n<p>\u00abQuienes atacan utilizan el c\u00f3digo y activan la cuenta ajena en un nuevo dispositivo para luego cometer diferentes delitos\u00bb, advierte la fiscal\u00eda.<\/p>\n<p>Lo que aconsejan es\u00a0<strong>\u00abactivar la &#8216;verificaci\u00f3n de dos pasos, ingresando para ello desde la aplicaci\u00f3n, a la secci\u00f3n &#8216;Cuenta&#8217;, ubicada dentro de la secci\u00f3n &#8216;Ajustes&#8217; o &#8216;Configuraci\u00f3n'\u00bb.<\/strong><\/p>\n<p>\u00abEl m\u00e1s importante de todos, creo yo, es asociar un email a la cuenta y activar la verificaci\u00f3n en dos pasos o segundo factor de autenticaci\u00f3n. Y, adem\u00e1s, NO (repito, NO) entregar los c\u00f3digos de verificaci\u00f3n para activar la cuenta a terceros, incluso aunque recibas un mensaje que aparenta ser de un conocido\u00bb, se\u00f1al\u00f3 Azzolin en su Twitter.<\/p>\n<p><strong>\u00abLa clave ac\u00e1 es la forma en la que los &#8216;malos&#8217; consiguen el c\u00f3digo de verificaci\u00f3n que manda WhatsApp para instalar una cuenta en un nuevo dispositivo. Se lo dan las propias v\u00edctimas\u00bb<\/strong>, coment\u00f3 el fiscal.<\/p>\n<p>Y explic\u00f3 que \u00ablos medios que usan para conseguirlo son, en las \u00faltimas semanas, principalmente dos\u00bb.<\/p>\n<p>\u00abEl primero es alrededor de una venta por internet. El supuesto comprador le dice al vendedor que le va a mandar un c\u00f3digo para cargar el GPS y llegar al lugar donde retira la mercader\u00eda o para transferirle el dinero\u00bb, explic\u00f3.<\/p>\n<p>\u00abEl segundo \u2013continu\u00f3-, un poco m\u00e1s artero en los tiempos que corren, es el c\u00f3digo de activaci\u00f3n de un turno para vacunarse contra el Covid-19, que le ten\u00e9s que pasar al &#8216;operador&#8217; que te llam\u00f3 supuestamente de alg\u00fan Ministerio de Salud\u00bb.<\/p>\n<p>En el \u00faltimo mensaje de su hilo de tuits, Azzolin concluy\u00f3:<strong>\u00a0\u00abSi tienen claro todo esto, cuidan sus claves como las llaves de su casa, no caer\u00edan nunca en este tipo de maniobras de ingenier\u00eda social, les propongo comentarles de esto a sus familiares y amigxs\u00bb.<\/strong><\/p>\n<p>Consultado por T\u00e9lam y a modo de conclusi\u00f3n, Azzolin asegur\u00f3 hoy que \u00ablo importante es que, por un lado, la gente que tiene cuentas, las proteja. Poner contrase\u00f1as robustas, activar el doble factor de identificaci\u00f3n y no entregar las claves ni el segundo factor de autentificaci\u00f3n, ni el c\u00f3digo de activaci\u00f3n a nadie\u00bb.<\/p>\n<p>\u00abEso permite que a uno no le roben la cuenta y de esa forma no estafen a tus contactos. Y si uno recibe estos mensajes, hay que ignorarlos, no caer en esas trampas\u00bb, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal Horacio Azzolin, titular de la Unidad Fiscal Especializada en Ciberdelincuencia (UFECI), alert\u00f3 a trav\u00e9s de su cuenta de Twitter sobre una nueva modalidad de fraude.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,26],"tags":[],"class_list":["post-65038","post","type-post","status-publish","format-standard","hentry","category-policiales","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar &quot;cara grande&quot; - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar &quot;cara grande&quot; - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El fiscal Horacio Azzolin, titular de la Unidad Fiscal Especializada en Ciberdelincuencia (UFECI), alert\u00f3 a trav\u00e9s de su cuenta de Twitter sobre una nueva modalidad de fraude.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T19:52:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/\",\"name\":\"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \\\"cara grande\\\" - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg\",\"datePublished\":\"2021-11-17T19:52:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage\",\"url\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg\",\"contentUrl\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \u00abcara grande\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \"cara grande\" - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/","og_locale":"es_ES","og_type":"article","og_title":"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \"cara grande\" - Noticias Radio Reflejos","og_description":"El fiscal Horacio Azzolin, titular de la Unidad Fiscal Especializada en Ciberdelincuencia (UFECI), alert\u00f3 a trav\u00e9s de su cuenta de Twitter sobre una nueva modalidad de fraude.\u00a0","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-11-17T19:52:51+00:00","og_image":[{"url":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/","name":"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \"cara grande\" - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg","datePublished":"2021-11-17T19:52:51+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#primaryimage","url":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg","contentUrl":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/61954130a7292_900.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/advierten-sobre-el-robo-de-cuentas-de-whatsapp-y-la-nueva-estafa-del-dolar-cara-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Advierten sobre el robo de cuentas de WhatsApp y la nueva estafa del d\u00f3lar \u00abcara grande\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=65038"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65038\/revisions"}],"predecessor-version":[{"id":65039,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65038\/revisions\/65039"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=65038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=65038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=65038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}