{"id":65028,"date":"2021-11-17T16:17:40","date_gmt":"2021-11-17T16:17:40","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=65028"},"modified":"2021-11-17T16:17:40","modified_gmt":"2021-11-17T16:17:40","slug":"habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","title":{"rendered":"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer"},"content":{"rendered":"<p>En el marco del D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, que se conmemora cada 25 de noviembre, la Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, llevar\u00e1 adelante una serie de actividades la semana pr\u00f3xima.<!--more--><\/p>\n<p>Del lunes 22 al viernes 26, se recibir\u00e1n donaciones para mujeres en situaci\u00f3n de salida de las violencias, como ropa para adultas, ni\u00f1os y adolescentes, alimentos no perecederos, \u00fatiles escolares, juguetes, pa\u00f1ales, ropa de cama y juegos de mesa.<\/p>\n<p>En Tornquist, las donaciones se recepcionar\u00e1n en la oficina del \u00e1rea de G\u00e9nero (V. Picado 111), de 8 a 19 hs; mientras que, en Sierra de la Ventana, ser\u00e1 en la sede de Desarrollo Social (Roca 145), de 8 a 12 hs.<\/p>\n<p>El martes 23, en tanto, a partir de las 17.30 hs se realizar\u00e1 una caminata desde la mencionada dependencia municipal hacia la senda peatonal \u2018Gerardo P. Rattero\u2019. Para esta actividad, que se organiza en conjunto con la Direcci\u00f3n de Deportes, se invita a quienes participen a llevar una prenda distintiva de color violeta.<\/p>\n<p>Ese d\u00eda tambi\u00e9n se distribuir\u00e1 folleter\u00eda informativa con d\u00edas, horarios, funciones y objetivos de la oficina local de g\u00e9nero.<\/p>\n<p>Adem\u00e1s, durante toda la semana, se iluminar\u00e1 el Palacio Municipal de color violeta.<\/p>\n<p><a title=\"25-nov\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/51686529596\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg\" alt=\"25-nov\" width=\"677\" height=\"800\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, que se conmemora cada 25 de noviembre, la Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, llevar\u00e1 adelante una serie de actividades la semana pr\u00f3xima.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,24,26],"tags":[],"class_list":["post-65028","post","type-post","status-publish","format-standard","hentry","category-municipales","category-politica","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"En el marco del D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, que se conmemora cada 25 de noviembre, la Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, llevar\u00e1 adelante una serie de actividades la semana pr\u00f3xima.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T16:17:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\",\"name\":\"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg\",\"datePublished\":\"2021-11-17T16:17:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage\",\"url\":\"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg\",\"contentUrl\":\"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","og_locale":"es_ES","og_type":"article","og_title":"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos","og_description":"En el marco del D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, que se conmemora cada 25 de noviembre, la Subsecretar\u00eda de Juventudes, Pol\u00edticas de G\u00e9nero y Diversidades de Tornquist Municipio, llevar\u00e1 adelante una serie de actividades la semana pr\u00f3xima.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-11-17T16:17:40+00:00","og_image":[{"url":"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","name":"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg","datePublished":"2021-11-17T16:17:40+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#primaryimage","url":"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg","contentUrl":"https:\/\/live.staticflickr.com\/65535\/51686529596_b8949b13eb_c.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/habra-actividades-por-el-dia-de-la-eliminacion-de-la-violencia-contra-la-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Habr\u00e1 actividades por el D\u00eda de la Eliminaci\u00f3n de la Violencia contra la Mujer"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=65028"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65028\/revisions"}],"predecessor-version":[{"id":65029,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/65028\/revisions\/65029"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=65028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=65028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=65028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}