{"id":64975,"date":"2021-11-16T17:31:06","date_gmt":"2021-11-16T17:31:06","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=64975"},"modified":"2021-11-16T17:31:06","modified_gmt":"2021-11-16T17:31:06","slug":"el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/","title":{"rendered":"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18"},"content":{"rendered":"<p>Seg\u00fan establece el C\u00f3digo Nacional Electoral, el conteo, a cargo del juzgado federal con competencia de cada distrito, debe inciarse pasadas las 48 horas de la actividad comicial, aunque en algunos casos\u00a0arrancar\u00e1 el mi\u00e9rcoles\u00a0a primera hora.<\/p>\n<div class=\"image\"><\/div>\n<div class=\"info\">\n<div class=\"time\"><\/div>\n<\/div>\n<div>\n<div class=\"wrapper-editable-content\">\n<div class=\"row\">\n<div class=\"container-md\">\n<div class=\"row\">\n<div class=\"col-md-10 offset-md-1 speak\">\n<div class=\"paragraph\">\n<figure class=\"mb-3\"><img decoding=\"async\" src=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg\" alt=\"El escrutinio definitivo comenzar el martes a las 18 en todo el pas a cargo de la Justicia nacional electoral\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>El escrutinio definitivo comenzar\u00e1 el martes a las 18 en todo el pa\u00eds a cargo de la Justicia nacional electoral.<\/figcaption><\/figure>\n<p>El\u00a0<strong>escrutinio definitivo comenzar\u00e1 este martes a las 18 horas<\/strong>\u00a0en la mayor\u00eda de las provincias, a cargo de la justicia nacional electoral, aunque en algunos distritos el recuento reci\u00e9n se<strong>\u00a0iniciar\u00e1 el pr\u00f3ximo mi\u00e9rcoles, como en el caso de Buenos Aires, Mendoza y Santiago del Estero<\/strong>.<\/p>\n<p>Seg\u00fan informaron fuentes de la\u00a0<strong>C\u00e1mara Nacional Electoral<\/strong>, el conteo definitivo de sufragios ser\u00e1 este martes desde las 18 horas y estar\u00e1 a cargo del juzgado federal con competencia electoral de cada distrito.<\/p>\n<p><strong>En algunos casos<\/strong>, sin embargo,<strong>\u00a0arrancar\u00e1 el mi\u00e9rcoles<\/strong>\u00a0a primera hora, se puntualiz\u00f3, en el marco de una normativa que establece el inicio del recuento en las 48 horas siguientes a la elecci\u00f3n general, de acuerdo con el C\u00f3digo Nacional Electoral.<\/p>\n<h2 class=\"\">Provincia de Buenos Aires<\/h2>\n<p>En el caso de la provincia de Buenos Aires, por ejemplo, el escrutinio comenzar\u00e1 el mi\u00e9rcoles en el centro cultural Pasaje Dardo Rocha, en La Plata, confirmaron este lunes fuentes de la justicia electoral bonaerense.<\/p>\n<p>El recuento de votos se iniciar\u00e1 a las 8 en el espacio ubicado en calle 50 entre 6 y 7 y habr\u00e1 un total de 100 mesas \u00abfuncionando en simult\u00e1neo\u00bb.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/EleccionesArgentina?src=hash&amp;ref_src=twsrc%5Etfw\">#EleccionesArgentina<\/a> <\/p>\n<p>Recepci\u00f3n de urnas en <a href=\"https:\/\/twitter.com\/hashtag\/BuenosAires?src=hash&amp;ref_src=twsrc%5Etfw\">#BuenosAires<\/a> para comenzar el Escrutinio Definitivo. <a href=\"https:\/\/t.co\/GO2q7HXKcW\">pic.twitter.com\/GO2q7HXKcW<\/a><\/p>\n<p>&mdash; C\u00e1mara Electoral (@CamaraElectoral) <a href=\"https:\/\/twitter.com\/CamaraElectoral\/status\/1460273051078115336?ref_src=twsrc%5Etfw\">November 15, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Con el objetivo de acelerar el proceso, el juez federal con competencia electoral,\u00a0<strong>Alejo Ramos Padilla<\/strong>, dispuso<strong>\u00a0incrementar en un 50% la cantidad de mesas<\/strong>\u00a0respecto de las elecciones primarias de septiembre, momento en que se comenz\u00f3 con 44 mesas y se termin\u00f3 con 63.<\/p>\n<p>Desde la Justicia remarcaron que si bien la duraci\u00f3n del escrutinio depender\u00e1 de la cantidad de mesas observadas que haya y de los pedidos de apertura, podr\u00eda concluirse en menos de una semana.<\/p>\n<p>Para ello, los empleados de la justicia electoral y los apoderados y representantes partidarios trabajar\u00e1n a diario entre las 8 y las 18 horas.<\/p>\n<h2 class=\"\">Santa Fe<\/h2>\n<p>En Santa Fe, el recuento tanto para cargos nacionales como comunales, tambi\u00e9n se iniciar\u00e1 este martes a las 18, en este caso en las instalaciones de la Secretar\u00eda Electoral, donde este lunes ya se encontraban en custodia las urnas, inform\u00f3 el titular del \u00e1rea, Pablo Ayala.<\/p>\n<figure class=\"mb-3\"><img decoding=\"async\" class=\" lazy \" src=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/11\/618fba898a8db_900.jpg\" alt=\"El escrutinio definitivo estar a cargo de la justicia nacional electoral Foto Victoria Egurza\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>El escrutinio definitivo estar\u00e1 a cargo de la justicia nacional electoral. (Foto: Victoria Egurza)<\/figcaption><\/figure>\n<p>El funcionario indic\u00f3 a T\u00e9lam que el conteo definitivo se iniciar\u00e1 con las urnas del departamento Belgrano, ya que se sigue un orden alfab\u00e9tico, y podr\u00eda concluir el s\u00e1bado.<\/p>\n<p>La diferencia con el escrutinio de las PASO, que se extendi\u00f3 entre el 15 y el 21 de septiembre, es que en esta ocasi\u00f3n se facilita la tarea por la menor cantidad de boletas en el caso de las legislativas nacionales, y de marcas en la boleta \u00fanica que se utiliz\u00f3 para la elecci\u00f3n de intendentes, concejales y autoridades comunales.<\/p>\n<p>La Secretar\u00eda Electoral de Santa Fe est\u00e1 recibiendo por estas horas las acreditaciones de los fiscales que controlar\u00e1n el recuento en representaci\u00f3n de los diferentes partidos y coaliciones que participaron de ambas contiendas.<\/p>\n<p>En el plano provincial, el domingo se eligieron intendentes en 14 municipios y se renovaron 210 concejales titulares y 184 suplentes en diferentes ciudades, adem\u00e1s de las autoridades en otras 306 comunas.<\/p>\n<h2 class=\"\">Entre R\u00edos<\/h2>\n<p>En Entre R\u00edos, la Secretar\u00eda Electoral Nacional con sede en la provincia, confirm\u00f3 este lunes a T\u00e9lam que este martes comenzar\u00e1, a las 18, el escrutinio de las actas electorales.<\/p>\n<p>Las urnas arribaron a la sede ubicada en la capital entrerriana y se espera la llegada de todos los telegramas para iniciar el escrutinio definitivo de los votos.<\/p>\n<h2 class=\"\">Neuqu\u00e9n<\/h2>\n<p>Este martes tambi\u00e9n Neuqu\u00e9n dar\u00e1 inicio a la revisi\u00f3n final de los resultados electorales. Desde la sede neuquina de la Secretar\u00eda Electoral Nacional indicaron a T\u00e9lam que en el gimnasio del Parque Central de la ciudad \u00abtrabajar\u00e1n siete mesas escrutadoras\u00bb.<\/p>\n<h2 class=\"\">R\u00edo Negro<\/h2>\n<p>De igual manera, el Juzgado Federal con Competencia Electoral de Viedma inform\u00f3 este lunes que el escrutinio definitivo de las elecciones legislativas nacionales comenzar\u00e1 este martes.<\/p>\n<figure class=\"mb-3\"><img decoding=\"async\" class=\" lazy \" src=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/615584b770026_900.jpg\" alt=\"El escrutinio definitivo comenzar el martes a las 18 en la mayora de las provincias\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>El escrutinio definitivo comenzar\u00e1 el martes a las 18 en la mayor\u00eda de las provincias.<\/figcaption><\/figure>\n<h2 class=\"\">Corrientes<\/h2>\n<p>El mismo esquema seguir\u00e1 la provincia de Corrientes, donde, seg\u00fan informaron fuentes oficiales, se iniciar\u00e1 el recuento este martes a las 18 en la Legislatura provincial.<\/p>\n<p>La Junta Electoral Nacional de Corrientes, presidida por la jueza de C\u00e1mara Mirtha Sotelo de Andreau, empezar\u00e1 el recuento de votos de las elecciones en la que se definieron tres cargos del Senado de la Naci\u00f3n y tres de Diputados, as\u00ed como autoridades municipales en 15 localidades.<\/p>\n<p>Adem\u00e1s de Buenos Aires, otras provincias que comenzar\u00e1n el conteo el mi\u00e9rcoles son Santiago del Estero y Mendoza.<\/p>\n<h2 class=\"\">Santiago del Estero<\/h2>\n<p>En Santiago del Estero el escrutinio se har\u00e1 en el centro de convenciones Forum, en la capital provincial, confirmaron fuentes del juzgado federal.<\/p>\n<p>Los apoderados de cada una de las listas que participaron de la contienda electoral participar\u00e1n del recuento junto a autoridades y empleados del juzgado federal y del Tribunal Electoral provincial.<\/p>\n<p>En caso de detectarse alguna diferencia mayor a cinco votos se proceder\u00e1 a abrir la urna para cotejar los n\u00fameros, se indic\u00f3.<\/p>\n<h2 class=\"\">jujuy<\/h2>\n<p>En Jujuy, por ejemplo, el Frente de Izquierda y los Trabajadores (FIT-U) advirti\u00f3 este lunes que \u00abseguir\u00e1 de cerca\u00bb el escrutinio definitivo que se iniciar\u00e1 el pr\u00f3ximo mi\u00e9rcoles, luego de denunciar que en los comicios del domingo \u00abse detectaron casos de suplantaci\u00f3n de boletas\u00bb con el objetivo de \u00abperjudicar\u00bb a ese espacio pol\u00edtico.<\/p>\n<p>Los candidatos de la izquierda cuya lista encabez\u00f3 el flamante diputado nacional electo, Alejandro Vilca, realizaron el domingo una denuncia ante la Justicia electoral por presunto cambio de boletas, tras lo cual el juzgado a cargo resolvi\u00f3 que se les d\u00e9 validez a las utilizadas en las PASO, al privilegiar que se respete la voluntad popular.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan establece el C\u00f3digo Nacional Electoral, el conteo, a cargo del juzgado federal con competencia de cada distrito, debe inciarse pasadas las 48 horas de la actividad comicial, aunque en algunos casos\u00a0arrancar\u00e1 el mi\u00e9rcoles\u00a0a primera hora. El escrutinio definitivo comenzar\u00e1 el martes a las 18 en todo el pa\u00eds a cargo de la Justicia nacional [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64975","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan establece el C\u00f3digo Nacional Electoral, el conteo, a cargo del juzgado federal con competencia de cada distrito, debe inciarse pasadas las 48 horas de la actividad comicial, aunque en algunos casos\u00a0arrancar\u00e1 el mi\u00e9rcoles\u00a0a primera hora. El escrutinio definitivo comenzar\u00e1 el martes a las 18 en todo el pa\u00eds a cargo de la Justicia nacional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-16T17:31:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/\",\"name\":\"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg\",\"datePublished\":\"2021-11-16T17:31:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage\",\"url\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg\",\"contentUrl\":\"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/","og_locale":"es_ES","og_type":"article","og_title":"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos","og_description":"Seg\u00fan establece el C\u00f3digo Nacional Electoral, el conteo, a cargo del juzgado federal con competencia de cada distrito, debe inciarse pasadas las 48 horas de la actividad comicial, aunque en algunos casos\u00a0arrancar\u00e1 el mi\u00e9rcoles\u00a0a primera hora. El escrutinio definitivo comenzar\u00e1 el martes a las 18 en todo el pa\u00eds a cargo de la Justicia nacional [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-11-16T17:31:06+00:00","og_image":[{"url":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/","name":"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18 - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage"},"thumbnailUrl":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg","datePublished":"2021-11-16T17:31:06+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#primaryimage","url":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg","contentUrl":"https:\/\/www.telam.com.ar\/thumbs\/bluesteel\/advf\/imagenes\/2021\/09\/6141fc7eeb977_900.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-escrutinio-definitivo-a-cargo-de-la-justicia-electoral-comenzara-este-martes-a-las-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El escrutinio definitivo, a cargo de la Justicia electoral, comenzar\u00e1 este martes a las 18"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/64975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=64975"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/64975\/revisions"}],"predecessor-version":[{"id":64977,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/64975\/revisions\/64977"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=64975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=64975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=64975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}