{"id":63645,"date":"2021-10-13T11:21:51","date_gmt":"2021-10-13T11:21:51","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=63645"},"modified":"2021-10-13T11:21:51","modified_gmt":"2021-10-13T11:21:51","slug":"quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/","title":{"rendered":"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero"},"content":{"rendered":"<div class=\"head-content\">\n<p>En el documento, que la cartera educativa provincial\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, se defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.<\/p>\n<div class=\"addthis_custom_sharing\" data-url=\"https:\/\/www.telam.com.ar\/notas\/202110\/571526-quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero.html\" data-title=\"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero\" data-description=\"En el documento, que la cartera educativa provincial\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, se defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.\">\n<div id=\"atstbx\" class=\"at-resp-share-element at-style-responsive addthis-smartlayers addthis-animated at4-show\" role=\"region\" aria-labelledby=\"at-34b23909-f37b-4b49-bec9-c5823c8d5b15\"><\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"main-content-block\">\n<div class=\"main-box clearfix\">\n<div class=\"wrapper-main-section clearfix\">\n<div class=\"wrapper-editable-content\">\n<div class=\"editable-content clearfix\">\n<div id=\"image\" class=\"image\">\n<div class=\"epigrafe\"><\/div>\n<\/div>\n<p>Los alumnos y alumnas de las escuelas de la provincia de Buenos Aires que no hayan podido recuperar saberes pendientes en las clases a contraturno y las dictadas los s\u00e1bados deber\u00e1n asistir a clases en febrero pr\u00f3ximo para poder promocionar el bienio 2020-2021.<\/p>\n<p>En tanto, aquellos<strong>\u00a0<\/strong>estudiantes secundarios que<strong>\u00a0cumplido el recuperatorio de febrero 2022 a\u00fan tengan trayectorias discontinuas o adeuden hasta 2 materias podr\u00e1n pasar de a\u00f1o<\/strong>\u00a0y seguir r<strong>ecuperando contenidos en el primer semestre<\/strong>\u00a0de 2022, inform\u00f3 la Direcci\u00f3n General de Cultura y Educaci\u00f3n bonaerense.<\/p>\n<p>As\u00ed lo establece\u00a0<strong>el documento que la cartera educativa provincial<\/strong>\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, donde defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.<\/p>\n<p>El documento, enviado a las instituciones educativas para el trabajo en las Jornadas Institucionales, establece claramente que las clases a contraturno de la jornada habitual y los s\u00e1bados son las instancias previstas de forma obligatoria para que quienes tengan saberes pendientes en una o m\u00e1s \u00e1reas curriculares puedan recuperarlos y acreditarlos.<\/p>\n<p>\u00abSi logran aprender todo lo requerido, promocionan el bienio en el mes de diciembre. En caso contrario, deben continuar asistiendo a las clases de fortalecimiento en febrero de 2022\u00bb, precis\u00f3 un comunicado de la cartera provincial.<\/p>\n<p>Para el proceso de evaluaci\u00f3n, se contin\u00faan utilizando las\u00a0<strong>tres categor\u00edas de valoraci\u00f3n pedag\u00f3gica<\/strong>\u00a0para las trayectorias educativas de las y los estudiantes utilizadas el a\u00f1o pasado.<\/p>\n<p>Se trata de la\u00a0<strong>Trayectoria educativa Avanzada (TEA); la Trayectoria educativa en Proceso (TEP) y la Trayectoria educativa Discontinua (TED).<\/strong><\/p>\n<p>El documento establece tambi\u00e9n que, para lograr la promoci\u00f3n\u00a0<strong>se debe tener aprobado al menos el 70% de los contenidos establecidos en el Curr\u00edculum Prioritario\u00a0<\/strong>para cada \u00e1rea curricular, considerando tanto la participaci\u00f3n como el desempe\u00f1o efectivo en las actividades escolares que da cuenta del avance en el aprendizaje de los contenidos propuestos.<\/p>\n<p>Con respecto a la promoci\u00f3n del a\u00f1o, el documento ejemplifica los escenarios posibles para los niveles Primario y Secundario.<\/p>\n<p><strong>En nivel Primario<\/strong>\u00a0ser\u00e1n promovidos en diciembre 2021 las y los estudiantes que tengan una trayectoria educativa avanzada (TEA) en el segundo informe 2021; y tambi\u00e9n lo ser\u00e1n los que habiendo tenido una trayectoria educativa en proceso (TEP) en el primer informe de este a\u00f1o, hayan participado regularmente de los encuentros de intensificaci\u00f3n en horarios de extensi\u00f3n del tiempo escolar, registrando un adecuado nivel de desempe\u00f1o y de ese modo hayan logrado una valoraci\u00f3n pedag\u00f3gica TEA en el segundo informe.<\/p>\n<p><strong>Del mismo modo, ser\u00e1n promovidos las y los estudiantes con trayectoria educativa discontinua (TED)\u00a0<\/strong>en el primer informe que se hayan revinculado con la asistencia diaria a la escuela y hayan participado regularmente de los encuentros de intensificaci\u00f3n en horarios de extensi\u00f3n del tiempo escolar, registrando un adecuado nivel de desempe\u00f1o y de ese modo hayan logrado una valoraci\u00f3n pedag\u00f3gica TEA en el segundo informe.<\/p>\n<p>\u00abLos y las estudiantes que habiendo tenido una trayectoria educativa en proceso o discontinua en la valoraci\u00f3n pedag\u00f3gica correspondiente al primer informe de este a\u00f1o, hayan participado regularmente de los encuentros de intensificaci\u00f3n en horarios de extensi\u00f3n del tiempo escolar, pero no alcanzaron un adecuado nivel de desempe\u00f1o y no hayan logrado una valoraci\u00f3n pedag\u00f3gica TEA en el segundo informe, no promocionar\u00e1n en diciembre sino que contar\u00e1n con una instancia en febrero para profundizar los saberes pendientes\u00bb, defini\u00f3 la cartera bonaerense.<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el documento, que la cartera educativa provincial\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, se defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-63645","post","type-post","status-publish","format-standard","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"En el documento, que la cartera educativa provincial\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, se defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T11:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/\",\"name\":\"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2021-10-13T11:21:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/","og_locale":"es_ES","og_type":"article","og_title":"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos","og_description":"En el documento, que la cartera educativa provincial\u00a0elabor\u00f3 y dio a conocer este martes a trav\u00e9s de la Resoluci\u00f3n 397\/21, se defini\u00f3 la evaluaci\u00f3n, acreditaci\u00f3n de los aprendizajes y promoci\u00f3n escolar para la finalizaci\u00f3n del bienio 2020-2021.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-10-13T11:21:51+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/","name":"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2021-10-13T11:21:51+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/quienes-no-recuperen-contenidos-en-clases-a-contraturno-deberan-asistir-a-clases-en-febrero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Quienes no recuperen contenidos en clases a contraturno deber\u00e1n asistir a clases en febrero"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=63645"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63645\/revisions"}],"predecessor-version":[{"id":63648,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63645\/revisions\/63648"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=63645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=63645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=63645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}