{"id":63286,"date":"2021-10-01T21:09:08","date_gmt":"2021-10-01T21:09:08","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=63286"},"modified":"2021-10-01T21:09:08","modified_gmt":"2021-10-01T21:09:08","slug":"vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/","title":{"rendered":"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os"},"content":{"rendered":"<div class=\"head-content\">\n<p>As\u00ed lo dispuso la Anmat\u00a0tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2. El pa\u00eds ya cuenta con un stock de \u00ab10 millones Sinopharm\u00bb y entre el 4 y el 11 de octubre recibir\u00e1 un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis a fin de este mes, asegur\u00f3 la ministra de Salud.<\/p>\n<div class=\"addthis_custom_sharing\" data-url=\"https:\/\/www.telam.com.ar\/notas\/202110\/570358-vacunas-coronavirus-sinopharm-ninos.html\" data-title=\"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os\" data-description=\"As\u00ed lo dispuso la Anmat\u00a0tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2. El pa\u00eds ya cuenta con un stock de &quot;10 millones Sinopharm&quot; y entre el 4 y el 11 de octubre recibir\u00e1 un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis a fin de este mes, asegur\u00f3 la ministra de Salud.\">\n<div id=\"atstbx\" class=\"at-resp-share-element at-style-responsive addthis-smartlayers addthis-animated at4-show\" role=\"region\" aria-labelledby=\"at-afe2e1ae-6b8e-4b52-8eb0-eb857ba45b0b\"><\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"main-content-block\">\n<div class=\"main-box clearfix\">\n<div class=\"wrapper-main-section clearfix\">\n<div class=\"wrapper-editable-content\">\n<div class=\"editable-content clearfix\">\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Entre el 24 y el 27 de este mes llegar\u00e1n vacunas Pfizer para ser aplicadas a un universo de 5 millones de adolescentes.. Foto: Presidencia.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg\" alt=\"Entre el 24 y el 27 de este mes llegar\u00e1n vacunas Pfizer para ser aplicadas a un universo de 5 millones de adolescentes.. Foto: Presidencia.\" \/><\/p>\n<div class=\"epigrafe\">Entre el 24 y el 27 de este mes llegar\u00e1n vacunas Pfizer para ser aplicadas a un universo de 5 millones de adolescentes.. Foto: Presidencia.<\/div>\n<\/div>\n<p>El Gobierno anunci\u00f3 que fue emitida una<strong>\u00a0autorizaci\u00f3n para vacunar contra el coronavirus a los ni\u00f1os de entre 3 y 11 a\u00f1os con dosis de la china Sinopharm<\/strong>, con el objetivo de completar la inmunizaci\u00f3n de esa franja etaria de la poblaci\u00f3n antes de fin de a\u00f1o.<\/p>\n<p>\u00abLa Argentina termina el 2021 con toda su poblaci\u00f3n de m\u00e1s de tres a\u00f1os cubierta y protegida. Contamos con el stock para iniciar esa vacunaci\u00f3n y completar los esquemas\u00bb, dijo la ministra de Salud, Carla Vizzotti en una conferencia de prensa junto al ministro de Educaci\u00f3n Jaime Perczyk.<\/p>\n<p>Vizzotti precis\u00f3 que\u00a0<strong>completar\u00e1 los esquemas de vacunaci\u00f3n de ni\u00f1os y adolescentes con vacunas Sinpharm y Pfizer.<\/strong><\/p>\n<blockquote><p>\u00abLa Argentina termina el 2021 con toda su poblaci\u00f3n de m\u00e1s de tres a\u00f1os cubierta y protegida\u00bb<\/p>\n<div class=\"sign\">CARLA VIZZOTTI<\/div>\n<\/blockquote>\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Vizzotti confirm\u00f3 que podr\u00e1n aplicarse vacunas Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/61377c28b7a6d_1004x565.jpg\" alt=\"Vizzotti confirm\u00f3 que podr\u00e1n aplicarse vacunas Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os.\" \/><\/p>\n<div class=\"epigrafe\">Vizzotti confirm\u00f3 que podr\u00e1n aplicarse vacunas Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os.<\/div>\n<\/div>\n<p>En el caso de las vacunas Sinopharm, explic\u00f3 que su utilizaci\u00f3n fue autorizada por la ANMAT tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2 y dijo que la\u00a0<strong>Argentina ya cuenta con un stock de \u00ab10 millones\u00bb<\/strong>, a las que se sumar\u00e1n \u00abentre el 4 y el 11 de octubre un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis a fin de este mes\u00bb.<\/p>\n<p>En cuanto a las Pfizer, Vizzotti adelant\u00f3 que entre el 24 y el 27 de este mes llegar\u00e1n dosis para ser aplicadas a un universo de 5 millones de adolescentes.<\/p>\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Foto: Diego Izquierdo.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/08\/6111325b4c2af_1004x565.jpg\" alt=\"Foto: Diego Izquierdo.\" \/><\/p>\n<div class=\"epigrafe\">Foto: Diego Izquierdo.<\/div>\n<\/div>\n<p>En este marco, Vizzotti,\u00a0<strong>anunci\u00f3 una convocatoria para el lunes del Consejo Federal de Salud<\/strong>\u00a0para evaluar c\u00f3mo siguen los pasos para la vacunaci\u00f3n de ni\u00f1os y j\u00f3venes contra el coronavirus, ya sea en las escuelas o en centros de inmunizaci\u00f3n.<\/p>\n<p>Por su parte, el ministro de Educaci\u00f3n Jaime Perczyk dijo que \u00abla vacunaci\u00f3n tiene que ver con recuperar presencialidad plena desde el nivel inicial, recuperar tiempos y aprendizajes en la escuela y la normalidad creciente en el campo educativo\u00bb.<\/p>\n<p>Agreg\u00f3 que la vacunaci\u00f3n \u00abaporta, tambi\u00e9n a recuperar a los chicos que se nos fueron del nivel educativo porque invit\u00e1ndolos a vacunarse van a volver a la escuela\u00bb.<\/p>\n<blockquote><p>\u00abLa vacunaci\u00f3n tiene que ver con recuperar presencialidad plena desde el nivel inicial, recuperar tiempos y aprendizajes\u00bb<\/p>\n<div class=\"sign\">JAIME PERCZYK<\/div>\n<\/blockquote>\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Foto: Horacio Culaciatti.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/08\/61099a8dcabea_1004x565.jpg\" alt=\"Foto: Horacio Culaciatti.\" \/><\/p>\n<div class=\"epigrafe\">Foto: Horacio Culaciatti.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo dispuso la Anmat\u00a0tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2. El pa\u00eds ya cuenta con un stock de \u00ab10 millones Sinopharm\u00bb y entre el 4 y el 11 de octubre recibir\u00e1 un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30],"tags":[],"class_list":["post-63286","post","type-post","status-publish","format-standard","hentry","category-politica","category-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"As\u00ed lo dispuso la Anmat\u00a0tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2. El pa\u00eds ya cuenta con un stock de \u00ab10 millones Sinopharm\u00bb y entre el 4 y el 11 de octubre recibir\u00e1 un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T21:09:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/\",\"name\":\"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg\",\"datePublished\":\"2021-10-01T21:09:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage\",\"url\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg\",\"contentUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos","og_description":"As\u00ed lo dispuso la Anmat\u00a0tras haberse realizado ensayos cl\u00ednicos de las fases 1 y 2. El pa\u00eds ya cuenta con un stock de \u00ab10 millones Sinopharm\u00bb y entre el 4 y el 11 de octubre recibir\u00e1 un lote de 1,5 mill\u00f3n m\u00e1s y otro de 1,6 millones, con lo que completar\u00e1 12 millones de dosis [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-10-01T21:09:08+00:00","og_image":[{"url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/","name":"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg","datePublished":"2021-10-01T21:09:08+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#primaryimage","url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg","contentUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/10\/615775762bb25.48.01_1004x565.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vizzotti-anuncio-que-se-podra-aplicar-la-vacuna-sinopharm-a-ninos-de-entre-3-y-11-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Vizzotti anunci\u00f3 que se podr\u00e1 aplicar la vacuna Sinopharm a ni\u00f1os de entre 3 y 11 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=63286"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63286\/revisions"}],"predecessor-version":[{"id":63288,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/63286\/revisions\/63288"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=63286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=63286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=63286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}