{"id":62966,"date":"2021-09-23T18:59:03","date_gmt":"2021-09-23T18:59:03","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=62966"},"modified":"2021-09-23T18:59:03","modified_gmt":"2021-09-23T18:59:03","slug":"rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/","title":{"rendered":"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz"},"content":{"rendered":"<div class=\"head-content\">\n<p>El actual presidente del m\u00e1ximo tribunal, Carlos Rosenkrantz, queda como vicepresidente. Ricardo Lorenzetti no particip\u00f3 del encuentro.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"main-content-block\">\n<div class=\"main-box clearfix\">\n<div class=\"wrapper-main-section clearfix\">\n<div class=\"wrapper-editable-content\">\n<div class=\"editable-content clearfix\">\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Rosatti es el nuevo presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg\" alt=\"Rosatti es el nuevo presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz\" \/><\/p>\n<div class=\"epigrafe\">Rosatti es el nuevo presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz<\/div>\n<div><\/div>\n<\/div>\n<p><strong>TELAM<\/strong> &#8211; El ministro de la Corte Suprema de Justicia <strong>Horacio Rosatti<\/strong>\u00a0es el nuevo presidente del alto tribunal, luego de ser propuesto por\u00a0<strong>Juan Carlos Maqueda<\/strong>\u00a0y apoyado por el actual presidente,\u00a0<strong>Carlos Rosenkrantz<\/strong>, que queda como vicepresidente.<\/p>\n<p><strong>Ricardo Lorenzetti<\/strong>\u00a0no particip\u00f3 del encuentro y por tal motivo,\u00a0<strong>Elena Highton<\/strong>\u00a0solicit\u00f3 una pr\u00f3rroga del acuerdo que no fue concedida por alcanzarse la mayor\u00eda de tres votos para elegir el nuevo titular del m\u00e1ximo tribunal.<\/p>\n<p>La reuni\u00f3n virtual se inici\u00f3 a las 12 de este jueves, como estaba previsto, pero los ministros dejaron constancia en el acuerdo de selecci\u00f3n del nuevo presidente que \u201ca las 10.34 horas el ministro Ricardo Lorenzetti comunic\u00f3 que se encuentra imposibilitado de asistir al presente acuerdo extraordinario convocado para el d\u00eda de la fecha en virtud de estar participando de las reuniones del UNIDROIT (Instituto Internacional para la Unificaci\u00f3n del Derecho Privado) y en las cuales act\u00faa en calidad de miembro del Governing Council\u201d.<\/p>\n<p>A rengl\u00f3n seguido, la acordada 18\/2021, se\u00f1al\u00f3 que \u201ca las 11.15 horas la ministra Elena Highton de Nolasco solicit\u00f3 la postergaci\u00f3n del acuerdo extraordinario por no estar presente el ministro Ricardo Lorenzetti\u201d.<\/p>\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Lorenzetti no particip\u00f3 del encuentro y por tal motivo, Highton solicit\u00f3 una pr\u00f3rroga del acuerdo que no fue concedida.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/editadas\/5f91613421395_1004x565.jpg\" alt=\"Lorenzetti no particip\u00f3 del encuentro y por tal motivo, Highton solicit\u00f3 una pr\u00f3rroga del acuerdo que no fue concedida.\" \/><\/p>\n<div class=\"epigrafe\">Lorenzetti no particip\u00f3 del encuentro y por tal motivo, Highton solicit\u00f3 una pr\u00f3rroga del acuerdo que no fue concedida.<\/div>\n<\/div>\n<p>A este pedido, el mismo Rosenkrantz defini\u00f3 que \u201cen virtud de que\u00a0<strong>la ausencia de alguno de los ministros no constituye un impedimento legal para la celebraci\u00f3n del acuerdo convocado, ser\u00e1 celebrado<\/strong>\u201d.<\/p>\n<p>De este modo, con la presencia de tres de los cinco miembros del tribunal,\u00a0<strong>Maqueda propuso el binomio Rosatti-Rosenkrantz<\/strong>\u00a0para la presidencia y vicepresidencia, respectivamente, f\u00f3rmula que fue aceptada por los involucrados.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El actual presidente del m\u00e1ximo tribunal, Carlos Rosenkrantz, queda como vicepresidente. Ricardo Lorenzetti no particip\u00f3 del encuentro.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,26],"tags":[],"class_list":["post-62966","post","type-post","status-publish","format-standard","hentry","category-politica","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El actual presidente del m\u00e1ximo tribunal, Carlos Rosenkrantz, queda como vicepresidente. Ricardo Lorenzetti no particip\u00f3 del encuentro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T18:59:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/\",\"name\":\"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg\",\"datePublished\":\"2021-09-23T18:59:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage\",\"url\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg\",\"contentUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/","og_locale":"es_ES","og_type":"article","og_title":"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos","og_description":"El actual presidente del m\u00e1ximo tribunal, Carlos Rosenkrantz, queda como vicepresidente. Ricardo Lorenzetti no particip\u00f3 del encuentro.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-09-23T18:59:03+00:00","og_image":[{"url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/","name":"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg","datePublished":"2021-09-23T18:59:03+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#primaryimage","url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg","contentUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/09\/614cb7b734349_1004x565.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/rosatti-fue-elegido-presidente-de-la-corte-suprema-con-el-apoyo-de-maqueda-y-rosenkrantz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Rosatti fue elegido presidente de la Corte Suprema con el apoyo de Maqueda y Rosenkrantz"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=62966"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62966\/revisions"}],"predecessor-version":[{"id":62967,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62966\/revisions\/62967"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=62966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=62966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=62966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}