{"id":62470,"date":"2021-09-07T20:13:52","date_gmt":"2021-09-07T20:13:52","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=62470"},"modified":"2021-09-07T20:49:42","modified_gmt":"2021-09-07T20:49:42","slug":"accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/","title":{"rendered":"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \u00abla gente entra al cuarto oscuro y vota sola\u00bb"},"content":{"rendered":"<p>Esta ma\u00f1ana conversamos con el Secretario de Gobierno y Seguridad, Ezequiel Gabella, para que nos informe acerca de los protocolos que se llevar\u00e1n a cabo en las elecciones del pr\u00f3ximo Domingo 12 de Septiembre. Adem\u00e1s, hace un descargo, como presidente de Acci\u00f3n por Tornquist, a partir de la salida de un comunicado que denunciaba que la agrupaci\u00f3n vecinal estaba repartiendo boletas cortadas.<!--more-->\u00abSi hay algo que caracteriz\u00f3 a este a\u00f1o y medio fue lo at\u00edpico. Se van a desarrollar las elecciones en un contexto complejo, porque siguen rigiendo muchas normas con los cuidados para la prevenci\u00f3n del Covid. Una de las caracter\u00edsticas que van a tener son el cumplimiento de cierto protocolo\u00bb present\u00f3 Ezequiel la tem\u00e1tica de la entrevista de esta ma\u00f1ana.<\/p>\n<p>\u00abEl tema es evitar el aglomeramiento de personas. La gente que va a estar esperando para votar va a tener que hacerlo afuera\u00bb explic\u00f3 una de las reglas a cumplir para estar en regla con el protocolo de votaci\u00f3n. Ezequiel explic\u00f3 que dicha situaci\u00f3n no es favorable, y que podr\u00eda resultar en muy pocos votantes en caso de mal tiempo, aunque vuelve a recordar que las elecciones son obligatorias. Adem\u00e1s, record\u00f3 que es obligatorio el uso de tapabocas, que se recomienda utilizar alcohol en gel y llevar una lapicera para realizar la firma de votaci\u00f3n.<\/p>\n<p>\u00abMuy probablemente en momentos pico, haya que realizar alg\u00fan corte de calle para facilitar espacio para que la gente haga la cola\u00bb tambi\u00e9n mencion\u00f3 aquellas situaciones que se est\u00e1n coordinando desde el \u00e1rea de Seguridad.<\/p>\n<p>\u00abPor una cuesti\u00f3n de plazo, no se lleg\u00f3 a tiempo a la impresi\u00f3n de boleta\u00bb coment\u00f3 acerca de la cuarta lista con representantes locales que muy probable aparezca en los cuartos oscuros el d\u00eda Domingo. En dicha lista, aparecen personas que nunca se postularon y sus nombres fueron colocados sin su consentimiento. Adem\u00e1s, aparecen personas ya fallecidas. Con respecto a esto, Ezequiel aclar\u00f3 que quiz\u00e1s para el d\u00eda Domingo se consiga una resoluci\u00f3n que impugne dicha boleta. \u00abEs una situaci\u00f3n que se va a resolver a \u00faltimo momento\u00bb.<\/p>\n<p>Sobre el final de la nota, Gabella aprovech\u00f3 para aclarar una situaci\u00f3n en la que un comunicado, emitido por otra agrupaci\u00f3n local, que declara que la agrupaci\u00f3n Acci\u00f3n por Tornquist estaba repartiendo boletas cortadas de otros frentes. \u00abQuiero dejar en claro dos situaciones. Una, confirmar que absolutamente nadie de nuestra agrupaci\u00f3n sali\u00f3 a repartir esa boleta y, si, fomentamos el corte de boleta, pero eso es algo aparte\u00bb desminti\u00f3 la denuncia.<\/p>\n<p>Las razones, por las cuales Ezequiel oficialmente manifiesta que esto no fue as\u00ed, se deben a que \u00abno vamos a ser tan bobos de hacer algo que perjudique a nuestro espacio pol\u00edtico\u00bb. \u00abEstamos convencidos de que la poblaci\u00f3n no es tonta, y, por m\u00e1s que les demos una boleta cortada, la gente entra al cuarto oscuro y vota sola\u00bb culmin\u00f3 con su descargo.<\/p>\n<p>Nota completa a continuaci\u00f3n:<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1120358803&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"fmreflejos 103.7\" href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\" target=\"_blank\" rel=\"noopener\">fmreflejos 103.7<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"Ezequiel Gabella\" href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\/ezequiel-gabella-603013363\" target=\"_blank\" rel=\"noopener\">Ezequiel Gabella<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana conversamos con el Secretario de Gobierno y Seguridad, Ezequiel Gabella, para que nos informe acerca de los protocolos que se llevar\u00e1n a cabo en las elecciones del pr\u00f3ximo Domingo 12 de Septiembre. Adem\u00e1s, hace un descargo, como presidente de Acci\u00f3n por Tornquist, a partir de la salida de un comunicado que denunciaba que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30],"tags":[48],"class_list":["post-62470","post","type-post","status-publish","format-standard","hentry","category-politica","category-salud","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: &quot;la gente entra al cuarto oscuro y vota sola&quot; - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: &quot;la gente entra al cuarto oscuro y vota sola&quot; - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Esta ma\u00f1ana conversamos con el Secretario de Gobierno y Seguridad, Ezequiel Gabella, para que nos informe acerca de los protocolos que se llevar\u00e1n a cabo en las elecciones del pr\u00f3ximo Domingo 12 de Septiembre. Adem\u00e1s, hace un descargo, como presidente de Acci\u00f3n por Tornquist, a partir de la salida de un comunicado que denunciaba que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T20:13:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-07T20:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/09\/gabella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"453\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/\",\"name\":\"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \\\"la gente entra al cuarto oscuro y vota sola\\\" - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2021-09-07T20:13:52+00:00\",\"dateModified\":\"2021-09-07T20:49:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \u00abla gente entra al cuarto oscuro y vota sola\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \"la gente entra al cuarto oscuro y vota sola\" - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/","og_locale":"es_ES","og_type":"article","og_title":"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \"la gente entra al cuarto oscuro y vota sola\" - Noticias Radio Reflejos","og_description":"Esta ma\u00f1ana conversamos con el Secretario de Gobierno y Seguridad, Ezequiel Gabella, para que nos informe acerca de los protocolos que se llevar\u00e1n a cabo en las elecciones del pr\u00f3ximo Domingo 12 de Septiembre. Adem\u00e1s, hace un descargo, como presidente de Acci\u00f3n por Tornquist, a partir de la salida de un comunicado que denunciaba que [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-09-07T20:13:52+00:00","article_modified_time":"2021-09-07T20:49:42+00:00","og_image":[{"width":453,"height":441,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/09\/gabella.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/","name":"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \"la gente entra al cuarto oscuro y vota sola\" - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2021-09-07T20:13:52+00:00","dateModified":"2021-09-07T20:49:42+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accion-por-tornquist-se-desliga-del-reparto-de-boletas-cortadas-la-gente-entra-al-cuarto-oscuro-y-vota-sola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Acci\u00f3n por Tornquist se desliga del reparto de boletas cortadas: \u00abla gente entra al cuarto oscuro y vota sola\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=62470"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62470\/revisions"}],"predecessor-version":[{"id":62477,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/62470\/revisions\/62477"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=62470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=62470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=62470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}