{"id":60013,"date":"2021-07-12T14:23:23","date_gmt":"2021-07-12T14:23:23","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=60013"},"modified":"2021-07-12T14:23:23","modified_gmt":"2021-07-12T14:23:23","slug":"informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/","title":{"rendered":"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires"},"content":{"rendered":"<p style=\"font-weight: 400;\">La Ley provincial N\u00b0 15.134 -conocida popularmente como Ley Micaela bonaerense- fue sancionada el 21 de marzo de 2019 y establece la capacitaci\u00f3n obligatoria en la tem\u00e1tica de g\u00e9nero y prevenci\u00f3n de violencias contra las mujeres para todas las personas que se desempe\u00f1en en la funci\u00f3n p\u00fablica en los tres poderes del Estado provincial (Ejecutivo, Legislativo y Judicial) cualquiera sea su nivel y jerarqu\u00eda.<!--more--><\/p>\n<p style=\"font-weight: 400;\">Al finalizar el a\u00f1o 2020, la Provincia de Buenos Aires cuenta con 859 formadoras y formadores en Ley Micaela Bonaerense a lo largo de todo su territorio.<\/p>\n<p style=\"font-weight: 400;\">Un dato destacable es la distribuci\u00f3n regional de las personas que finalizaron y aprobaron los cursos del Programa Formadoras y Formadores, donde el 15,7% corresponden a la Regi\u00f3n Sexta.<\/p>\n<p style=\"font-weight: 400;\">Desde la Coordinaci\u00f3n de la Sexta Regi\u00f3n\u00a0compartimos la publicaci\u00f3n del Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires.<\/p>\n<p style=\"font-weight: 400;\">Tenemos el orgullo de ser, la segunda regi\u00f3n en inscriptos que terminaron la capacitaci\u00f3n, despu\u00e9s de la Regi\u00f3n Primera<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/ministeriodelasmujeres.gba.gob.ar\/gestor\/uploads\/ley%20micaela%20-%20municipios%20-%20informe%202020.pdf\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ministeriodelasmujeres.gba.gob.ar\/gestor\/uploads\/ley%2520micaela%2520-%2520municipios%2520-%2520informe%25202020.pdf&amp;source=gmail&amp;ust=1626184689464000&amp;usg=AFQjCNGIC-Gtdvs1NxRdoTD-AIjdkOU23w\">https:\/\/ministeriodelasmujeres.gba.gob.ar\/gestor\/uploads\/ley%20micaela%20-%20municipios%20-%20informe%202020.pdf<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Silvia ZABALLA. Coordinadora de la Sexta Regi\u00f3n del Ministerio de las Mujeres, Pol\u00edticas de G\u00e9nero y Diversidad Sexual, PBA.<\/p>\n<p style=\"font-weight: 400;\">2216 16-0276<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ley provincial N\u00b0 15.134 -conocida popularmente como Ley Micaela bonaerense- fue sancionada el 21 de marzo de 2019 y establece la capacitaci\u00f3n obligatoria en la tem\u00e1tica de g\u00e9nero y prevenci\u00f3n de violencias contra las mujeres para todas las personas que se desempe\u00f1en en la funci\u00f3n p\u00fablica en los tres poderes del Estado provincial (Ejecutivo, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-60013","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Ley provincial N\u00b0 15.134 -conocida popularmente como Ley Micaela bonaerense- fue sancionada el 21 de marzo de 2019 y establece la capacitaci\u00f3n obligatoria en la tem\u00e1tica de g\u00e9nero y prevenci\u00f3n de violencias contra las mujeres para todas las personas que se desempe\u00f1en en la funci\u00f3n p\u00fablica en los tres poderes del Estado provincial (Ejecutivo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-12T14:23:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/\",\"name\":\"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2021-07-12T14:23:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/","og_locale":"es_ES","og_type":"article","og_title":"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos","og_description":"La Ley provincial N\u00b0 15.134 -conocida popularmente como Ley Micaela bonaerense- fue sancionada el 21 de marzo de 2019 y establece la capacitaci\u00f3n obligatoria en la tem\u00e1tica de g\u00e9nero y prevenci\u00f3n de violencias contra las mujeres para todas las personas que se desempe\u00f1en en la funci\u00f3n p\u00fablica en los tres poderes del Estado provincial (Ejecutivo, [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-07-12T14:23:23+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/","name":"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2021-07-12T14:23:23+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/informe-2020-del-programa-de-formacion-de-formadoras-es-en-ley-micaela-bonaerense-para-los-municipios-de-la-provincia-de-buenos-aires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Informe 2020 del Programa de Formaci\u00f3n de Formadoras\/es en Ley Micaela bonaerense para los Municipios de la Provincia de Buenos Aires"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/60013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=60013"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/60013\/revisions"}],"predecessor-version":[{"id":60015,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/60013\/revisions\/60015"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=60013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=60013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=60013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}