{"id":59759,"date":"2021-07-05T15:23:44","date_gmt":"2021-07-05T15:23:44","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=59759"},"modified":"2021-07-05T15:23:44","modified_gmt":"2021-07-05T15:23:44","slug":"juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/","title":{"rendered":"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura"},"content":{"rendered":"<p>La Secretar\u00eda de Desarrollo de Tornquist Municipio, mediante la Direcci\u00f3n de Cultura, defini\u00f3 la fecha de la Etapa Distrital de los Juegos Bonaerenses 2021 de las disciplinas culturales.<!--more--><\/p>\n<p>Ser\u00e1 el domingo 25 de julio de manera virtual y competir\u00e1n alrededor de 20 inscriptos en las siguientes actividades: Pintura Sub 16, Pintura PCD, Dibujo Sub 15, Dibujo Sub 18, Poes\u00eda Sub 15, Poes\u00eda\u00a0Sub 18, Cuento Sub 18 y Danzas Folkl\u00f3ricas\u00a0Sub 18.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Desarrollo de Tornquist Municipio, mediante la Direcci\u00f3n de Cultura, defini\u00f3 la fecha de la Etapa Distrital de los Juegos Bonaerenses 2021 de las disciplinas culturales.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-59759","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Desarrollo de Tornquist Municipio, mediante la Direcci\u00f3n de Cultura, defini\u00f3 la fecha de la Etapa Distrital de los Juegos Bonaerenses 2021 de las disciplinas culturales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T15:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/\",\"name\":\"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2021-07-05T15:23:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/","og_locale":"es_ES","og_type":"article","og_title":"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos","og_description":"La Secretar\u00eda de Desarrollo de Tornquist Municipio, mediante la Direcci\u00f3n de Cultura, defini\u00f3 la fecha de la Etapa Distrital de los Juegos Bonaerenses 2021 de las disciplinas culturales.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-07-05T15:23:44+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/","name":"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2021-07-05T15:23:44+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/juegos-bonaerenses-tiene-fecha-la-etapa-distrital-de-cultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Juegos Bonaerenses: Tiene fecha la etapa Distrital de Cultura"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/59759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=59759"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/59759\/revisions"}],"predecessor-version":[{"id":59760,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/59759\/revisions\/59760"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=59759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=59759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=59759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}