{"id":57770,"date":"2021-05-31T19:34:55","date_gmt":"2021-05-31T19:34:55","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=57770"},"modified":"2021-05-31T19:34:55","modified_gmt":"2021-05-31T19:34:55","slug":"la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/","title":{"rendered":"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal"},"content":{"rendered":"<div class=\"head-content\">\n<p>El laboratorio oficial brasile\u00f1o Fiocruz advirti\u00f3 sobre un recrudecimiento de la pandemia durante junio y julio\u00a0 -repitiendo el colapso sanitario registrado en febrero, marzo y abril \u00fatimos- debido a que 20 capitales est\u00e1n con m\u00e1s de 80% de ocupaci\u00f3n hospitalaria.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"main-content-block\">\n<div class=\"main-box clearfix\">\n<div class=\"wrapper-main-section clearfix\">\n<div class=\"wrapper-editable-content\">\n<div class=\"editable-content clearfix\">\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"Bolsonaro sue\u00f1a con volver a entregarle la Copa Am\u00e9rica a Neymar, como en el 2019.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png\" alt=\"Bolsonaro sue\u00f1a con volver a entregarle la Copa Am\u00e9rica a Neymar, como en el 2019.\" \/><\/p>\n<div class=\"epigrafe\">Bolsonaro sue\u00f1a con volver a entregarle la Copa Am\u00e9rica a Neymar, como en el 2019.<\/div>\n<\/div>\n<p>Brasil se encuentra en las puertas de una tercera ola de coronavirus prevista por el laboratorio oficial Fiocruz, de Ministerio de Salud, para mediados de junio,\u00a0<a href=\"https:\/\/www.telam.com.ar\/notas\/202105\/556053-copa-america-brasil.html\" target=\"_blank\" rel=\"noopener\">justamente para cuando comience la Copa Am\u00e9rica<\/a>, que volver\u00e1 ser realizada en tierras brasile\u00f1as, segundo pa\u00eds en muertes y tercero en casos de Covid-19 en el mundo.<\/p>\n<p><strong>El ofrecimiento de Brasil como sede alternativa ocurre en el peor momento de popularidad del presidente Jair Bolsonaro<\/strong>, quien el s\u00e1bado r<a href=\"https:\/\/www.telam.com.ar\/notas\/202105\/556059-bolsonarismo-polarizacion-lula-2022.html\" target=\"_blank\" rel=\"noopener\">ecibi\u00f3 las m\u00e1s importantes manifestaciones en su contra\u00a0<\/a>desde que se inici\u00f3 la pandemia, en reclamo de su renuncia o juicio pol\u00edtico.<\/p>\n<p>Seg\u00fan los medios brasile\u00f1os, el ofrecimiento que hizo Brasil a la Conmebol incluye la buena experiencia de la edici\u00f3n 2019 ganada por los locales ante Per\u00fa y la aceptaci\u00f3n de que\u00a0<strong>la final deber\u00e1 ser en el estadio Maracan\u00e1 de R\u00edo de Janeiro.<\/strong><\/p>\n<p><strong>R\u00edo de Janeiro es la segunda ciudad en muertes por COVID-19 y tambi\u00e9n es donde m\u00e1s avanzada est\u00e1 la vacunaci\u00f3n<\/strong>, ya que este lunes comenz\u00f3 la inmunizaci\u00f3n de personas entre 59 y 18 a\u00f1os que no pertenezcan a grupos de riesgo.<\/p>\n<div class=\"auth\">Situaci\u00f3n sanitaria<\/div>\n<div id=\"image\" class=\"image\"><img decoding=\"async\" title=\"En medio del peor momento de sus popularidad, Bolsonaro recurre al f\u00fatbol a meses de las elecciones presidenciales del 2022.\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2021\/05\/60b405b18268d_1004x565.jpg\" alt=\"En medio del peor momento de sus popularidad, Bolsonaro recurre al f\u00fatbol a meses de las elecciones presidenciales del 2022.\" \/><\/p>\n<div class=\"epigrafe\">En medio del peor momento de sus popularidad, Bolsonaro recurre al f\u00fatbol a meses de las elecciones presidenciales del 2022.<\/div>\n<\/div>\n<p>El pa\u00eds acaba de salir de la segunda ola de Covid a fines de abril y con el levantamiento de las cuarentenas volvieron a subir los casos y las hospitalizaciones.\u00a0<strong>Brasil tiene 461.931 muertos y m\u00e1s de 16,5 millones de infectados acumulados.<\/strong><\/p>\n<p>El laboratorio oficial brasile\u00f1o Fiocruz alert\u00f3 el jueves sobre un recrudecimiento de la pandemia durante junio y julio a ra\u00edz de que actualmente se puede repetir el colapso sanitario registrado en febrero, marzo y abril debido a que 20 capitales est\u00e1n con m\u00e1s de 80% de ocupaci\u00f3n hospitalaria.<\/p>\n<p>El estado de Paran\u00e1, por ejemplo, fronterizo con Argentina y Paraguay, est\u00e1 con fila de 1400 pacientes para camas de UTI, seg\u00fan la secretar\u00eda de salud.<\/p>\n<p>Seg\u00fan Fiocruz,\u00a0<strong>la mortalidad se estabiliz\u00f3 en un promedio diario de unas 1.900 personas, menos que en abril, r\u00e9cord de fallecidos, pero dos veces superior que en el pico de la pandemia de 2020.<\/strong><\/p>\n<p>\u00abSe prev\u00e9 que en las pr\u00f3ximas dos semanas aumente a 2.000 \u00f3 2.300 muertos diarios debido al aumento de los contagios\u00bb, asegur\u00f3 el informe oficial, que pide el cese de aglomeraciones, revisar las flexibilizaciones de cuarentenas y la l\u00f3gica para levantarlas y acudir r\u00e1pidamente a instalar m\u00e1s equipamientos de terapia intensiva para pacientes con Covid.<\/p>\n<p><strong>El estado de San Pablo posterg\u00f3 dos semanas m\u00e1s el toque de queda nocturno\u00a0<\/strong>y las restricciones al comercio al llegar al 80% de ocupaci\u00f3n de camas de terapia intensiva.<\/p>\n<blockquote><p>Los estados con m\u00e1s del 95% por de ocupaci\u00f3n hospitalaria son Paran\u00e1, Santa Catarina, Bah\u00eda, Para\u00edba, Pernambuco, Rio Grande do Norte, Sergipe, Cear\u00e1, Brasilia, Mato Grosso do Sul, R\u00eco de Janeiro, San Pablo y Minas Gerais<\/p><\/blockquote>\n<p>Amazonas, que vivi\u00f3 dos colapsos y en enero crisis por falta de ox\u00edgeno para pacientes, tiene ocupaci\u00f3n por debajo del 60%,al igual que Acre, en la frontera con Bolivia y Per\u00fa.<\/p>\n<p><strong>La transmisi\u00f3n de la Copa Am\u00e9rica en Brasil, as\u00ed como la Copa Libertadores, ha cambiado de manos en Brasil: la TV Globo, la m\u00e1s poderosa del pa\u00eds, perdi\u00f3 los derechos frente a la cuarta emisora abierta, SBT, del magnate bolsonarista Silvio Santos, suegro del ministro de Comunicaciones, Fabio Faria.<\/strong><\/p>\n<p>Los medios ponen a las sedes m\u00e1s ociosas como candidatas a recibir a las selecciones, como Natal, Brasilia, Manaos y Cuiab\u00e1, con estadio modernos patr\u00f3n FIFA construidos para el Mundial 2014.<\/p>\n<p>El gobierno se encuentra bajo investigaci\u00f3n del Senado por su rol frente a la pandemia.<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<h4>Por Pablo Giuliano para TELAM<\/h4>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El laboratorio oficial brasile\u00f1o Fiocruz advirti\u00f3 sobre un recrudecimiento de la pandemia durante junio y julio\u00a0 -repitiendo el colapso sanitario registrado en febrero, marzo y abril \u00fatimos- debido a que 20 capitales est\u00e1n con m\u00e1s de 80% de ocupaci\u00f3n hospitalaria.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,24],"tags":[],"class_list":["post-57770","post","type-post","status-publish","format-standard","hentry","category-deportes","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El laboratorio oficial brasile\u00f1o Fiocruz advirti\u00f3 sobre un recrudecimiento de la pandemia durante junio y julio\u00a0 -repitiendo el colapso sanitario registrado en febrero, marzo y abril \u00fatimos- debido a que 20 capitales est\u00e1n con m\u00e1s de 80% de ocupaci\u00f3n hospitalaria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T19:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/\",\"name\":\"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png\",\"datePublished\":\"2021-05-31T19:34:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage\",\"url\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png\",\"contentUrl\":\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/","og_locale":"es_ES","og_type":"article","og_title":"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos","og_description":"El laboratorio oficial brasile\u00f1o Fiocruz advirti\u00f3 sobre un recrudecimiento de la pandemia durante junio y julio\u00a0 -repitiendo el colapso sanitario registrado en febrero, marzo y abril \u00fatimos- debido a que 20 capitales est\u00e1n con m\u00e1s de 80% de ocupaci\u00f3n hospitalaria.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2021-05-31T19:34:55+00:00","og_image":[{"url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/","name":"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png","datePublished":"2021-05-31T19:34:55+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#primaryimage","url":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png","contentUrl":"https:\/\/www.telam.com.ar\/advf\/imagenes\/2019\/07\/5d1c1a7c5f10c_1004x565.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-copa-america-llega-a-brasil-a-la-par-del-alerta-por-una-tercera-ola-letal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"La Copa Am\u00e9rica llega a Brasil a la par del alerta por una tercera ola letal"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/57770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=57770"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/57770\/revisions"}],"predecessor-version":[{"id":57772,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/57770\/revisions\/57772"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=57770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=57770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=57770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}