{"id":54265,"date":"2017-03-29T08:34:46","date_gmt":"2017-03-29T11:34:46","guid":{"rendered":"http:\/\/noticiasradioreflejos.com.ar\/noticias\/?p=8476"},"modified":"2017-03-29T08:34:46","modified_gmt":"2017-03-29T11:34:46","slug":"se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/","title":{"rendered":"Se viene el 81\u00b0 Abierto Nacional de Golf \u00abSemana Santa 2017\u00bb"},"content":{"rendered":"<p><a title=\"afiche semana santa 2017\" href=\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"float: left;\" title=\"afiche semana santa 2017\" src=\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\" alt=\"afiche semana santa 2017\" width=\"457\" height=\"640\" \/><\/a>A partir del 8 de abril, el Golf Club Sierra de la Ventana ser\u00e1 nuevamente sede del 81\u00b0 Abierto Nacional \u00abSemana Santa 2017\u00bb.<br \/>\nCon un programa que abre con la disputa de la Copa Diego Meyer el 8 y finalizando el s\u00e1bado 15 el tradicional Abierto Nacional a 54 hoyos medal play para todas las categor\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 8 de abril, el Golf Club Sierra de la Ventana ser\u00e1 nuevamente sede del 81\u00b0 Abierto Nacional \u00abSemana Santa 2017\u00bb. Con un programa que abre con la disputa de la Copa Diego Meyer el 8 y finalizando el s\u00e1bado 15 el tradicional Abierto Nacional a 54 hoyos medal play para todas las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-54265","post","type-post","status-publish","format-standard","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se viene el 81\u00b0 Abierto Nacional de Golf &quot;Semana Santa 2017&quot; - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se viene el 81\u00b0 Abierto Nacional de Golf &quot;Semana Santa 2017&quot; - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"A partir del 8 de abril, el Golf Club Sierra de la Ventana ser\u00e1 nuevamente sede del 81\u00b0 Abierto Nacional \u00abSemana Santa 2017\u00bb. Con un programa que abre con la disputa de la Copa Diego Meyer el 8 y finalizando el s\u00e1bado 15 el tradicional Abierto Nacional a 54 hoyos medal play para todas las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-29T11:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/\",\"name\":\"Se viene el 81\u00b0 Abierto Nacional de Golf \\\"Semana Santa 2017\\\" - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\",\"datePublished\":\"2017-03-29T11:34:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage\",\"url\":\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\",\"contentUrl\":\"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se viene el 81\u00b0 Abierto Nacional de Golf \u00abSemana Santa 2017\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se viene el 81\u00b0 Abierto Nacional de Golf \"Semana Santa 2017\" - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/","og_locale":"es_ES","og_type":"article","og_title":"Se viene el 81\u00b0 Abierto Nacional de Golf \"Semana Santa 2017\" - Noticias Radio Reflejos","og_description":"A partir del 8 de abril, el Golf Club Sierra de la Ventana ser\u00e1 nuevamente sede del 81\u00b0 Abierto Nacional \u00abSemana Santa 2017\u00bb. Con un programa que abre con la disputa de la Copa Diego Meyer el 8 y finalizando el s\u00e1bado 15 el tradicional Abierto Nacional a 54 hoyos medal play para todas las [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2017-03-29T11:34:46+00:00","og_image":[{"url":"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/","name":"Se viene el 81\u00b0 Abierto Nacional de Golf \"Semana Santa 2017\" - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage"},"thumbnailUrl":"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg","datePublished":"2017-03-29T11:34:46+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#primaryimage","url":"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg","contentUrl":"http:\/\/farm4.staticflickr.com\/3952\/33588352211_3d1bbd326a_z.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/se-viene-el-81-abierto-nacional-de-golf-semana-santa-2017-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Se viene el 81\u00b0 Abierto Nacional de Golf \u00abSemana Santa 2017\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/54265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=54265"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/54265\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=54265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=54265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=54265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}