{"id":46424,"date":"2020-08-31T22:04:17","date_gmt":"2020-09-01T01:04:17","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=46424"},"modified":"2020-08-31T22:04:17","modified_gmt":"2020-09-01T01:04:17","slug":"tornquist-supero-el-centenar-de-contagiados-con-coronavirus","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/","title":{"rendered":"Tornquist super\u00f3 el centenar de contagiados con coronavirus."},"content":{"rendered":"<p>Tres nuevos casos positivos en el reporte de esta noche ubican el total de contagiados en 101 personas de los cuales 57 ya se han recuperado.<!--more--><\/p>\n<p>Cerca e las 22 horas de este lunes 31 de agosto el municipio de Tornquist inform\u00f3 que el n\u00famero de contagiados sobrepasa el centenar de personas en el distrito.<br \/>\nDe los cuales 57 se encuentran recuperados, 42 activos, 2 fallecieron, 7 sospechosos esperan el resultado del hisopado, 163 ya fueron descartados y 185 se encuentran en aislamiento preventivo.<\/p>\n<p><a href=\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_s.jpg\" title=\"2020-08-31_09-55-52\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg\" width=\"1024\" height=\"1024\" alt=\"2020-08-31_09-55-52\" title=\"2020-08-31_09-55-52\" class=\"aligncenter\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres nuevos casos positivos en el reporte de esta noche ubican el total de contagiados en 101 personas de los cuales 57 ya se han recuperado.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-46424","post","type-post","status-publish","format-standard","hentry","category-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Tres nuevos casos positivos en el reporte de esta noche ubican el total de contagiados en 101 personas de los cuales 57 ya se han recuperado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T01:04:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/\",\"name\":\"Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg\",\"datePublished\":\"2020-09-01T01:04:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage\",\"url\":\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg\",\"contentUrl\":\"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tornquist super\u00f3 el centenar de contagiados con coronavirus.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos","og_description":"Tres nuevos casos positivos en el reporte de esta noche ubican el total de contagiados en 101 personas de los cuales 57 ya se han recuperado.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2020-09-01T01:04:17+00:00","og_image":[{"url":"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/","name":"Tornquist super\u00f3 el centenar de contagiados con coronavirus. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage"},"thumbnailUrl":"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg","datePublished":"2020-09-01T01:04:17+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#primaryimage","url":"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg","contentUrl":"http:\/\/live.staticflickr.com\/65535\/50292592117_7e9bd76b68_b.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/tornquist-supero-el-centenar-de-contagiados-con-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Tornquist super\u00f3 el centenar de contagiados con coronavirus."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/46424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=46424"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/46424\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=46424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=46424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=46424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}