{"id":21062,"date":"2018-04-25T10:13:34","date_gmt":"2018-04-25T13:13:34","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=21062"},"modified":"2018-04-25T10:13:34","modified_gmt":"2018-04-25T13:13:34","slug":"atencion-del-centro-de-jubilados-de-villa-ventana","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/","title":{"rendered":"Atenci\u00f3n del Centro de Jubilados de Villa Ventana"},"content":{"rendered":"<p>La Comisi\u00f3n Directiva del Centro de Jubilados de VILLA VENTANA recibe a sus asociados y jubilados o pensionados todos los jueves de 16 hs a 18 hs, para brindar informaci\u00f3n y atender sus inquietudes. <!--more--><br \/>\nAquel que no pueda acercarse puede mandar a otra persona.<br \/>\nEstamos en nuestra sede del Sal\u00f3n Parroquial de nuestra Capilla. Cruz del Sur y Hornero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Directiva del Centro de Jubilados de VILLA VENTANA recibe a sus asociados y jubilados o pensionados todos los jueves de 16 hs a 18 hs, para brindar informaci\u00f3n y atender sus inquietudes.<\/p>\n","protected":false},"author":3,"featured_media":17024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-21062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Directiva del Centro de Jubilados de VILLA VENTANA recibe a sus asociados y jubilados o pensionados todos los jueves de 16 hs a 18 hs, para brindar informaci\u00f3n y atender sus inquietudes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T13:13:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/\",\"name\":\"Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg\",\"datePublished\":\"2018-04-25T13:13:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg\",\"width\":526,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atenci\u00f3n del Centro de Jubilados de Villa Ventana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/","og_locale":"es_ES","og_type":"article","og_title":"Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos","og_description":"La Comisi\u00f3n Directiva del Centro de Jubilados de VILLA VENTANA recibe a sus asociados y jubilados o pensionados todos los jueves de 16 hs a 18 hs, para brindar informaci\u00f3n y atender sus inquietudes.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-04-25T13:13:34+00:00","og_image":[{"width":526,"height":395,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/","name":"Atenci\u00f3n del Centro de Jubilados de Villa Ventana - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg","datePublished":"2018-04-25T13:13:34+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2017\/12\/Villa-Ventana-00.jpg","width":526,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/atencion-del-centro-de-jubilados-de-villa-ventana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Atenci\u00f3n del Centro de Jubilados de Villa Ventana"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/21062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=21062"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/21062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/17024"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=21062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=21062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=21062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}