{"id":21055,"date":"2018-04-25T10:04:02","date_gmt":"2018-04-25T13:04:02","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=21055"},"modified":"2018-04-25T10:04:02","modified_gmt":"2018-04-25T13:04:02","slug":"un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/","title":{"rendered":"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces."},"content":{"rendered":"<p><a title=\"31242768_10214948966616475_1974550114131247104_n\" href=\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"float: left;\" title=\"31242768_10214948966616475_1974550114131247104_n\" src=\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\" alt=\"31242768_10214948966616475_1974550114131247104_n\" width=\"375\" height=\"500\" \/><\/a>El hecho ocurri\u00f3 a las 21,15 hs en Av. Sarmiento frente a la Plaza de la rotonda de San Bernardo. El conductor y su hija fueron atendidos en la Unidad Sanitaria.<br \/>\nUn <strong>Fiat Palio<\/strong>\u00a0conducido por<strong> H\u00e9ctor Demestri<\/strong>, embisti\u00f3 un tubo de hormig\u00f3n que se encontraba en medio de la Av. Sarmiento, a metros de la Plaza del Barrio San Bernardo en Sierra de la Ventana.<!--more--> El hecho se produjo cuando otro veh\u00edculo, circulando en contramano, sorprende a<strong> H\u00e9ctor Demestri<\/strong>, vecino de la localidad, que no tuvo m\u00e1s alternativa que hacer una brusca maniobra y terminar chocando contra el obst\u00e1culo.<br \/>\nEn el momento del accidente llov\u00eda y la calle se encontraba embarrada.<br \/>\nLos ocupantes del Palio fueron trasladados a la Unidad Sanitaria local donde recibieron atenci\u00f3n m\u00e9dica sin registrar lesiones graves.<br \/>\nEl veh\u00edculo qued\u00f3 seriamente da\u00f1ado en su frente y parabrisas. Vecinos testigos del hecho salieron a buscar al otro veh\u00edculo, que se dio a la fuga.<br \/>\nLa obra de desag\u00fces pluviales en la localidad comenz\u00f3 en el mes de diciembre del a\u00f1o pasado y a medida que avanza, va dejando de estos obst\u00e1culos por todas las calles donde se realiza. Son pozos conocidos como \u00abBocas de Tormentas\u00bb que llevar\u00e1n alguna tapa met\u00e1lica, pero de momento se encuentran abiertas, se\u00f1alizadas con caballetes y mallas pl\u00e1sticas de color naranja, pero en algunos casos se observan tubos grandes a manera de alerta sobre el lugar en obra, y justamente en uno de \u00e9stos, se produjo el siniestro de anoche.<br \/>\nDemestri manifest\u00f3 a nuestro medio que la polic\u00eda local no le tom\u00f3 la denuncia \u00abporque no hubo lesiones\u00bb.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hecho ocurri\u00f3 a las 21,15 hs en Av. Sarmiento frente a la Plaza de la rotonda de San Bernardo. El conductor y su hija fueron atendidos en la Unidad Sanitaria. Un Fiat Palio\u00a0conducido por H\u00e9ctor Demestri, embisti\u00f3 un tubo de hormig\u00f3n que se encontraba en medio de la Av. Sarmiento, a metros de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-21055","post","type-post","status-publish","format-standard","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El hecho ocurri\u00f3 a las 21,15 hs en Av. Sarmiento frente a la Plaza de la rotonda de San Bernardo. El conductor y su hija fueron atendidos en la Unidad Sanitaria. Un Fiat Palio\u00a0conducido por H\u00e9ctor Demestri, embisti\u00f3 un tubo de hormig\u00f3n que se encontraba en medio de la Av. Sarmiento, a metros de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T13:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/\",\"name\":\"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\",\"datePublished\":\"2018-04-25T13:04:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage\",\"url\":\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\",\"contentUrl\":\"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/","og_locale":"es_ES","og_type":"article","og_title":"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos","og_description":"El hecho ocurri\u00f3 a las 21,15 hs en Av. Sarmiento frente a la Plaza de la rotonda de San Bernardo. El conductor y su hija fueron atendidos en la Unidad Sanitaria. Un Fiat Palio\u00a0conducido por H\u00e9ctor Demestri, embisti\u00f3 un tubo de hormig\u00f3n que se encontraba en medio de la Av. Sarmiento, a metros de la [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-04-25T13:04:02+00:00","og_image":[{"url":"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/","name":"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage"},"thumbnailUrl":"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg","datePublished":"2018-04-25T13:04:02+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#primaryimage","url":"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg","contentUrl":"http:\/\/farm1.staticflickr.com\/955\/40974862454_830c364cd0.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/un-automovil-choco-contra-un-tubo-de-la-obra-de-desbragues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Un autom\u00f3vil choc\u00f3 contra un tubo de la obra de desag\u00fces."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/21055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=21055"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/21055\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=21055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=21055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=21055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}