{"id":20814,"date":"2018-04-17T07:57:35","date_gmt":"2018-04-17T10:57:35","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=20814"},"modified":"2018-04-17T07:57:35","modified_gmt":"2018-04-17T10:57:35","slug":"hechos-policiales-con-demorados-en-sierra-de-la-ventana","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/","title":{"rendered":"Hechos policiales con demorados en Sierra de la Ventana."},"content":{"rendered":"<p>La Subestaci\u00f2n de Polic\u00eca de sierra de la Ventana informa sobre actuaciones realizadas durante el fin de semana en la localidad.<!--more--><br \/>\n<strong>Parte Policial<\/strong>: Llevo a conocimiento de ese medio de prensa que durante el fin de semana, en distintos operativos de prevenci\u00f3n llevados a cabo por personal de esta Dependencia, se procedi\u00f3, el d\u00eda S\u00e1bado 14 del corriente a las 23:00 horas, a la Detenci\u00f3n del ciudadano CURINO DIEGO, de 37 a\u00f1os de edad, domiciliado en Bah\u00eda Blanca, quien viajaba a bordo de omnibus de la empresa La Estrella-El Condor, desde Bah\u00eda Blanca hacia esta localidad, en estado de ebriedad y produciendo desorden en el interior del micro, alterando y provocando un gran malestar en los pasajeros, por lo que se le labraron actuaciones por INFRACCION A LOS ARTICULOS 72 y 74 INCISO A DE LA LEY 8031, con intervenci\u00f3n del Juzgado de Paz Letrado de Tornquist.-<br \/>\nEn otro de los operativos de nocturnidad llevados a cabo, el d\u00eda Domingo 15 del mes y a\u00f1o en curso, a las 05:00 horas, en zona c\u00e9ntrica de esta localidad, se observo mediante las c\u00e1maras de seguridad municipales, dos masculinos que presentaban una actitud sospechosa, ya que caminaban en forma err\u00e1tica hacia varios lados, por lo que se dispuso personal policial para interceptarlos, identific\u00e1ndoselos como FABRICIO SCROFANI de 25 a\u00f1os, oriundo de la localidad de Claypole, Buenos Aires y CASTILLO FRANCO de 23 a\u00f1os, con domicilio en Bah\u00eda Blanca, secuestr\u00e1ndose en poder de los mismos 16 gramos de Marihuana y elementos para su consumo, labr\u00e1ndose actuaciones por INFRACCION A LA LEY 23.737 con intervenci\u00f3n de la Unidad Funcional de Instrucci\u00f3n y Juicio Nro. 19 del Departamento Judicial Bah\u00eda Blanca.-<br \/>\nSubestaci\u00f3n de Polic\u00eda Comunal Sierra de la Ventana, Abril 16 de 2018.-<br \/>\nFIRMADO: SUBCOMISARIO GONZALO M. SANDOBAL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Subestaci\u00f2n de Polic\u00eca de sierra de la Ventana informa sobre actuaciones realizadas durante el fin de semana en la localidad.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-20814","post","type-post","status-publish","format-standard","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Subestaci\u00f2n de Polic\u00eca de sierra de la Ventana informa sobre actuaciones realizadas durante el fin de semana en la localidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-17T10:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/\",\"name\":\"Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2018-04-17T10:57:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hechos policiales con demorados en Sierra de la Ventana.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/","og_locale":"es_ES","og_type":"article","og_title":"Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos","og_description":"La Subestaci\u00f2n de Polic\u00eca de sierra de la Ventana informa sobre actuaciones realizadas durante el fin de semana en la localidad.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-04-17T10:57:35+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/","name":"Hechos policiales con demorados en Sierra de la Ventana. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2018-04-17T10:57:35+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hechos-policiales-con-demorados-en-sierra-de-la-ventana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Hechos policiales con demorados en Sierra de la Ventana."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/20814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=20814"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/20814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=20814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=20814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=20814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}