{"id":20799,"date":"2018-04-16T17:48:22","date_gmt":"2018-04-16T20:48:22","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=20799"},"modified":"2018-04-16T17:48:22","modified_gmt":"2018-04-16T20:48:22","slug":"mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/","title":{"rendered":"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante"},"content":{"rendered":"<p>\u201cLa unidad de un pueblo permite su fortalecimiento y su crecimiento como comunidad\u201d<br \/>\nLa fecha fundacional de la ciudad de Tornquist se debe a que el 17 de abril de 1883 don Ernesto Tornquist manda a construir la primera edificaci\u00f3n, que fue el almac\u00e9n de ramos generales y la casa del administrador de Estancias y Colonias Tornquist.<!--more--><br \/>\nLa ciudad cumple 135 a\u00f1os de vida, y cuenta con un gran futuro por su ubicaci\u00f3n privilegiada, en un entorno natural maravilloso, pero tambi\u00e9n por su gente y sus instituciones, que supieron crear el entorno necesario para desarrollar una comunidad que enorgullece a sus habitantes.<br \/>\nCon motivo de celebrarse el 17 de abril un nuevo aniversario de la Ciudad de Tornquist, los integrantes del Honorable Concejo Deliberante desean enviar un caluroso saludo a todos sus pobladores, y los anima a seguir trabajando por el desarrollo y crecimiento de esta hermosa comunidad. Que esta fecha sea un motivo de festejo y alegr\u00eda.<br \/>\n\u00a1Tornquist, Feliz Aniversario!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa unidad de un pueblo permite su fortalecimiento y su crecimiento como comunidad\u201d La fecha fundacional de la ciudad de Tornquist se debe a que el 17 de abril de 1883 don Ernesto Tornquist manda a construir la primera edificaci\u00f3n, que fue el almac\u00e9n de ramos generales y la casa del administrador de Estancias y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-20799","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"\u201cLa unidad de un pueblo permite su fortalecimiento y su crecimiento como comunidad\u201d La fecha fundacional de la ciudad de Tornquist se debe a que el 17 de abril de 1883 don Ernesto Tornquist manda a construir la primera edificaci\u00f3n, que fue el almac\u00e9n de ramos generales y la casa del administrador de Estancias y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-16T20:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/\",\"name\":\"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2018-04-16T20:48:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/","og_locale":"es_ES","og_type":"article","og_title":"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos","og_description":"\u201cLa unidad de un pueblo permite su fortalecimiento y su crecimiento como comunidad\u201d La fecha fundacional de la ciudad de Tornquist se debe a que el 17 de abril de 1883 don Ernesto Tornquist manda a construir la primera edificaci\u00f3n, que fue el almac\u00e9n de ramos generales y la casa del administrador de Estancias y [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-04-16T20:48:22+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/","name":"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2018-04-16T20:48:22+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/mensaje-por-aniversario-de-tornquist-honorable-concejo-deliberante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Mensaje por aniversario de Tornquist, Honorable Concejo Deliberante"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/20799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=20799"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/20799\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=20799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=20799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=20799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}