{"id":18899,"date":"2018-02-16T10:14:54","date_gmt":"2018-02-16T13:14:54","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=18899"},"modified":"2018-02-16T10:14:54","modified_gmt":"2018-02-16T13:14:54","slug":"el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/","title":{"rendered":"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada."},"content":{"rendered":"<p><a title=\"WhatsApp Image 2018-02-16 at 07.30.56\" href=\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" title=\"WhatsApp Image 2018-02-16 at 07.30.56\" src=\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\" alt=\"WhatsApp Image 2018-02-16 at 07.30.56\" width=\"500\" height=\"333\" \/><\/a>Sigue siendo preocupante la situaci\u00f3n por el incendio, que llega a su segundo d\u00eda consumiendo miles de hect\u00e1reas en el cord\u00f3n serrano.<br \/>\n<strong>Gustavo De Vizia<\/strong>, Jefe del Cuerpo de Bomberos Voluntarios de Sierra de la Ventana, nos describe esta ma\u00f1ana d\u00f3nde se despliegan los esfuerzos para que el fuego no da\u00f1e los campos linderos a los cerros que arden en forma irrefrenable.<!--more--><br \/>\nEn estos momentos, dotaciones de bomberos de toda la regi\u00f3n esperan que el fuego baje por el sector de La Florida, en el l\u00edmite entre Sierras Grandes, La Josefina y Santo Tom\u00e1s de las Sierras.<br \/>\nLos aviones no pueden operar por las condiciones clim\u00e1ticas reinantes y el gran viento, y para hoy esperan m\u00e1s ayuda de helic\u00f3pteros y aviones, \u00absi es que pueden operar\u00bb, afirm\u00f3 De Vizia.<br \/>\n\u00abEl cansancio a medida que pasan las horas se siente m\u00e1s\u00bb, destac\u00f3 el Jefe, asegurando que los bomberos est\u00e1n todos bien y que seguimos trabajando para terminar con esto\u00bb.<br \/>\nEn la ma\u00f1ana de hoy no dan respiro las llamas que siguen devorando todo a su paso. Ayer fue muy angustiante la situaci\u00f3n vivida frente a los portones del Cerro Ventana. Bomberos y muchos particulares pudieron lograr que el fuego no pase hacia el interior del monumento natural pero todo qued\u00f3 devastado inclusive los montes de pinos que ardieron por completo.<br \/>\nAhora en ese sector que est\u00e1 cercano a San Andr\u00e9s de las Sierras, esperan que el fuego que baja lentamente por el cerro frente al puesto de Funke, pueda ser controlado y no pase a la zona urbana.<br \/>\nEs m\u00e1s complicada la situaci\u00f3n hacia el sector lindero al Cerro Tres Picos en los establecimientos Santo Tom\u00e1s de Las Sierras, Cerros Colorados y otros campos que fueron afectados por este gran incendio. Inclusive Estancia Funke sufre grandes p\u00e9rdidas.<br \/>\nLas im\u00e1genes enviadas desde el aire dan cuenta de c\u00f3mo avanzan los frentes descontrolados a pesar del gran operativo que existe. Hoy se espera que tambi\u00e9n lleguen los helic\u00f3pteros para que se sumen a los aviones hidrantes, para ver si las condiciones permiten trabajar debido al fuerte viento que tiene rotaciones permanentes.<br \/>\nLas lluvias no aparecen y esto complica a\u00fan m\u00e1s la situaci\u00f3n; se espera inestabilidad para la noche y madrugada del s\u00e1bado e inclusive el domingo, aunque literalmente es una \u201cLoter\u00eda\u201d porque s\u00f3lo en el a\u00f1o cayeron 13 mil\u00edmetros.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/400520142&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><br \/>\nFotos:Martin Haag<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sigue siendo preocupante la situaci\u00f3n por el incendio, que llega a su segundo d\u00eda consumiendo miles de hect\u00e1reas en el cord\u00f3n serrano. Gustavo De Vizia, Jefe del Cuerpo de Bomberos Voluntarios de Sierra de la Ventana, nos describe esta ma\u00f1ana d\u00f3nde se despliegan los esfuerzos para que el fuego no da\u00f1e los campos linderos a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-18899","post","type-post","status-publish","format-standard","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Sigue siendo preocupante la situaci\u00f3n por el incendio, que llega a su segundo d\u00eda consumiendo miles de hect\u00e1reas en el cord\u00f3n serrano. Gustavo De Vizia, Jefe del Cuerpo de Bomberos Voluntarios de Sierra de la Ventana, nos describe esta ma\u00f1ana d\u00f3nde se despliegan los esfuerzos para que el fuego no da\u00f1e los campos linderos a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T13:14:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/\",\"name\":\"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\",\"datePublished\":\"2018-02-16T13:14:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage\",\"url\":\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\",\"contentUrl\":\"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/","og_locale":"es_ES","og_type":"article","og_title":"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos","og_description":"Sigue siendo preocupante la situaci\u00f3n por el incendio, que llega a su segundo d\u00eda consumiendo miles de hect\u00e1reas en el cord\u00f3n serrano. Gustavo De Vizia, Jefe del Cuerpo de Bomberos Voluntarios de Sierra de la Ventana, nos describe esta ma\u00f1ana d\u00f3nde se despliegan los esfuerzos para que el fuego no da\u00f1e los campos linderos a [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-02-16T13:14:54+00:00","og_image":[{"url":"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/","name":"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage"},"thumbnailUrl":"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg","datePublished":"2018-02-16T13:14:54+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#primaryimage","url":"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg","contentUrl":"http:\/\/farm5.staticflickr.com\/4724\/26426620188_ff7ed0839a.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-fuego-continua-por-el-cordon-serrano-en-direccion-al-sur-y-la-situacion-es-muy-complicada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El fuego contin\u00faa por el cord\u00f3n serrano en direcci\u00f3n al sur y la situaci\u00f3n es muy complicada."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=18899"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18899\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=18899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=18899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=18899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}