{"id":18812,"date":"2018-02-14T18:32:50","date_gmt":"2018-02-14T21:32:50","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=18812"},"modified":"2018-02-14T18:32:50","modified_gmt":"2018-02-14T21:32:50","slug":"comenzo-un-incendio-en-el-parque-tornquist","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/","title":{"rendered":"Comenz\u00f3 un incendio en el Parque Tornquist"},"content":{"rendered":"<p>El fuego comenz\u00f3 en una alcantarilla frente al acceso al Abra de la Ventana en cercan\u00edas del ingreso al sector del Parque Provincial \u00abErnesto Tornquist\u00bb, frente al cerro Bah\u00eda Blanca.<br \/>\nR\u00e1pidamente las llamas alcanzaron el ca\u00f1ad\u00f3n y con los fuertes vientos comenzaron a avanzar hacia las cumbres del cord\u00f3n serrano.<br \/>\nTrabajan intensamente Bomberos Voluntarios de Villa Ventana, Sierra de la Ventana y Tornquist .<br \/>\nLas condiciones de sequ\u00eda y vientos con r\u00e1fagas de m\u00e1s de 50 km\/h hacen incontrolable el siniestro.<br \/>\nAmpliaremos.!<br \/>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-18812-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/wp-content\/uploads\/2018\/02\/VID-20180214-WA0030.mp4?_=1\" \/><a href=\"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/wp-content\/uploads\/2018\/02\/VID-20180214-WA0030.mp4\">http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/wp-content\/uploads\/2018\/02\/VID-20180214-WA0030.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fuego comenz\u00f3 en una alcantarilla frente al acceso al Abra de la Ventana en cercan\u00edas del ingreso al sector del Parque Provincial \u00abErnesto Tornquist\u00bb, frente al cerro Bah\u00eda Blanca. R\u00e1pidamente las llamas alcanzaron el ca\u00f1ad\u00f3n y con los fuertes vientos comenzaron a avanzar hacia las cumbres del cord\u00f3n serrano. Trabajan intensamente Bomberos Voluntarios de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-18812","post","type-post","status-publish","format-standard","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El fuego comenz\u00f3 en una alcantarilla frente al acceso al Abra de la Ventana en cercan\u00edas del ingreso al sector del Parque Provincial \u00abErnesto Tornquist\u00bb, frente al cerro Bah\u00eda Blanca. R\u00e1pidamente las llamas alcanzaron el ca\u00f1ad\u00f3n y con los fuertes vientos comenzaron a avanzar hacia las cumbres del cord\u00f3n serrano. Trabajan intensamente Bomberos Voluntarios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-14T21:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/\",\"name\":\"Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2018-02-14T21:32:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comenz\u00f3 un incendio en el Parque Tornquist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/","og_locale":"es_ES","og_type":"article","og_title":"Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos","og_description":"El fuego comenz\u00f3 en una alcantarilla frente al acceso al Abra de la Ventana en cercan\u00edas del ingreso al sector del Parque Provincial \u00abErnesto Tornquist\u00bb, frente al cerro Bah\u00eda Blanca. R\u00e1pidamente las llamas alcanzaron el ca\u00f1ad\u00f3n y con los fuertes vientos comenzaron a avanzar hacia las cumbres del cord\u00f3n serrano. Trabajan intensamente Bomberos Voluntarios de [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-02-14T21:32:50+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/","name":"Comenz\u00f3 un incendio en el Parque Tornquist - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2018-02-14T21:32:50+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/comenzo-un-incendio-en-el-parque-tornquist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Comenz\u00f3 un incendio en el Parque Tornquist"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=18812"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18812\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=18812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=18812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=18812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}