{"id":18644,"date":"2018-02-08T08:28:11","date_gmt":"2018-02-08T11:28:11","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=18644"},"modified":"2018-02-08T08:28:11","modified_gmt":"2018-02-08T11:28:11","slug":"hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/","title":{"rendered":"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades"},"content":{"rendered":"<p>Hoy jueves se inicia un paro de 48 horas de parte de los empleados del Banco Provincia, en protesta por la ley que reform\u00f3 la caja jubilatoria de los trabajadores de esa entidad crediticia, seg\u00fan iniciativa de la gobernadora Mar\u00eda Eugenia Vidal. Pero adem\u00e1s, ma\u00f1ana viernes se realizar\u00e1 un paro de todo el gremio bancario, que afectar\u00e1 las operaciones en el sistema, seguro en los bancos p\u00fablicos y tal vez no tanto en los bancos privados.<!--more--><br \/>\n\u201cAnte la falta de avances y el final de la conciliaci\u00f3n, se dispuso un paro de 48 horas para este jueves y viernes, y paro de 48 horas para jueves y viernes de la semana que viene\u201d dijeron fuentes gremiales del Bapro.<br \/>\nEl paro de la semana que viene se pegar\u00e1 adem\u00e1s a los feriados de carnaval, por lo que en las sucursales del Bapro no habr\u00e1 atenci\u00f3n (o, como m\u00ednimo, estar\u00e1 complicada) desde el 8 al 13 de febrero, inclusive. La Asociaci\u00f3n Bancaria, adem\u00e1s, ya program\u00f3 dos jornadas de paro m\u00e1s, para el 19 y 20 de febrero.<br \/>\nDINERO EN LOS CAJEROS AUTOM\u00c1TICOS<br \/>\nAnte ese escenario, los usuarios podr\u00edan llegar a tener dificultades para hacerse de efectivo. Las redes Banelco y Link recordaron que sus clientes tienen la posibilidad de hacer extracciones en diferentes comercios, como supermercados, farmacias o estaciones de servicio, con un l\u00edmite de hasta $ 5.000 por operaci\u00f3n.<br \/>\nEste dinero se solicita directamente en la caja del establecimiento, que procesar\u00e1 la operaci\u00f3n entregando billetes contra el d\u00e9bito autom\u00e1tico en la cuenta del usuario. Adem\u00e1s, los bancos prev\u00e9n una recarga especial de sus cajeros autom\u00e1ticos.<br \/>\nFuente: Clar\u00edn<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy jueves se inicia un paro de 48 horas de parte de los empleados del Banco Provincia, en protesta por la ley que reform\u00f3 la caja jubilatoria de los trabajadores de esa entidad crediticia, seg\u00fan iniciativa de la gobernadora Mar\u00eda Eugenia Vidal. Pero adem\u00e1s, ma\u00f1ana viernes se realizar\u00e1 un paro de todo el gremio bancario, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-18644","post","type-post","status-publish","format-standard","hentry","category-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Hoy jueves se inicia un paro de 48 horas de parte de los empleados del Banco Provincia, en protesta por la ley que reform\u00f3 la caja jubilatoria de los trabajadores de esa entidad crediticia, seg\u00fan iniciativa de la gobernadora Mar\u00eda Eugenia Vidal. Pero adem\u00e1s, ma\u00f1ana viernes se realizar\u00e1 un paro de todo el gremio bancario, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-08T11:28:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/\",\"name\":\"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2018-02-08T11:28:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/","og_locale":"es_ES","og_type":"article","og_title":"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos","og_description":"Hoy jueves se inicia un paro de 48 horas de parte de los empleados del Banco Provincia, en protesta por la ley que reform\u00f3 la caja jubilatoria de los trabajadores de esa entidad crediticia, seg\u00fan iniciativa de la gobernadora Mar\u00eda Eugenia Vidal. Pero adem\u00e1s, ma\u00f1ana viernes se realizar\u00e1 un paro de todo el gremio bancario, [&hellip;]","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2018-02-08T11:28:11+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/","name":"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2018-02-08T11:28:11+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hoy-para-el-banco-provincia-manana-se-suman-el-resto-de-las-entidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Hoy para el Banco Provincia: ma\u00f1ana se suman el resto de las entidades"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=18644"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/18644\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=18644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=18644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=18644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}