{"id":17548,"date":"2017-12-27T22:25:42","date_gmt":"2017-12-28T01:25:42","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=17548"},"modified":"2017-12-27T22:25:42","modified_gmt":"2017-12-28T01:25:42","slug":"viernes-29-atencion-al-publico-hasta-las-10-00hs","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/","title":{"rendered":"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs."},"content":{"rendered":"<p>Tornquist municipio informa que, por cierre de ejercicio, el pr\u00f3ximo viernes 29 la atenci\u00f3n al p\u00fablico ser\u00e1 hasta las 10.00 hs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tornquist municipio informa que, por cierre de ejercicio, el pr\u00f3ximo viernes 29 la atenci\u00f3n al p\u00fablico ser\u00e1 hasta las 10.00 hs.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-17548","post","type-post","status-publish","format-standard","hentry","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Tornquist municipio informa que, por cierre de ejercicio, el pr\u00f3ximo viernes 29 la atenci\u00f3n al p\u00fablico ser\u00e1 hasta las 10.00 hs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-28T01:25:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/\",\"name\":\"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2017-12-28T01:25:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/","og_locale":"es_ES","og_type":"article","og_title":"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos","og_description":"Tornquist municipio informa que, por cierre de ejercicio, el pr\u00f3ximo viernes 29 la atenci\u00f3n al p\u00fablico ser\u00e1 hasta las 10.00 hs.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2017-12-28T01:25:42+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/","name":"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2017-12-28T01:25:42+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/viernes-29-atencion-al-publico-hasta-las-10-00hs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Viernes 29: atenci\u00f3n al p\u00fablico hasta las 10.00hs."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/17548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=17548"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/17548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=17548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=17548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=17548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}