{"id":17164,"date":"2017-12-14T08:30:11","date_gmt":"2017-12-14T11:30:11","guid":{"rendered":"http:\/\/www.noticiasradioreflejos.com.ar\/noticias\/?p=17164"},"modified":"2017-12-14T08:30:11","modified_gmt":"2017-12-14T11:30:11","slug":"accidente-de-camiones-en-la-ruta-35","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/","title":{"rendered":"Accidente de camiones en la ruta 35."},"content":{"rendered":"<p><a title=\"34279981-cc57-45fe-a114-88cf3cdb5a7f\" href=\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"float: left;\" title=\"34279981-cc57-45fe-a114-88cf3cdb5a7f\" src=\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\" alt=\"34279981-cc57-45fe-a114-88cf3cdb5a7f\" width=\"500\" height=\"375\" \/><\/a>En la tarde de este mi\u00e9rcoles alrededor de la hora 16.30, se produjo una violenta colisi\u00f3n en el kil\u00f3metro 63 de la ruta nacional 35 en jurisdicci\u00f3n del partido de Tornquist cuando dos camiones protagonizaron un accidente.<!--more--><br \/>\nSeg\u00fan inform\u00f3 a nuestro medio el comisario Daniel Perez un cami\u00f3n cerealero ford cargo(AA425YY) conducido por Hugo Dante Zambrano(50) oriundo de Santa Rosa(LP), intenta subir a la ruta en direcci\u00f3n Pu\u00e1n-Bah\u00eda Blanca cuando es impactado por otro cami\u00f3n que circulaba por la carretera. Se trataba de un VW 1720(KFL 593) solo chasis, al mando de Alfredo N\u00e9stor Garc\u00eda(45) de la empresa av\u00edcola de Bah\u00eda Blanca \u201cEl Peregrino\u201d transportando pollos y derivados.<br \/>\nA pesar del tremendo impacto ambos choferes no sufrieron lesiones. El conductor Alfredo Garc\u00eda en observaci\u00f3n en el Hospital Municipal de Bah\u00eda Blanca por precauci\u00f3n.<br \/>\nLa ruta qued\u00f3 liberada luego del trabajo de polic\u00eda,salud y bomberos.<br \/>\n<a title=\"a55d5b7b-58b1-4e06-86c0-0ffed2d45f7c\" href=\"http:\/\/farm5.staticflickr.com\/4737\/27272194349_af91fcbdcc_z.jpg\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"a55d5b7b-58b1-4e06-86c0-0ffed2d45f7c\" src=\"http:\/\/farm5.staticflickr.com\/4737\/27272194349_af91fcbdcc_z.jpg\" alt=\"a55d5b7b-58b1-4e06-86c0-0ffed2d45f7c\" width=\"640\" height=\"480\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la tarde de este mi\u00e9rcoles alrededor de la hora 16.30, se produjo una violenta colisi\u00f3n en el kil\u00f3metro 63 de la ruta nacional 35 en jurisdicci\u00f3n del partido de Tornquist cuando dos camiones protagonizaron un accidente.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-17164","post","type-post","status-publish","format-standard","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accidente de camiones en la ruta 35. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accidente de camiones en la ruta 35. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"En la tarde de este mi\u00e9rcoles alrededor de la hora 16.30, se produjo una violenta colisi\u00f3n en el kil\u00f3metro 63 de la ruta nacional 35 en jurisdicci\u00f3n del partido de Tornquist cuando dos camiones protagonizaron un accidente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-14T11:30:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/\",\"name\":\"Accidente de camiones en la ruta 35. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\",\"datePublished\":\"2017-12-14T11:30:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage\",\"url\":\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\",\"contentUrl\":\"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accidente de camiones en la ruta 35.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accidente de camiones en la ruta 35. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/","og_locale":"es_ES","og_type":"article","og_title":"Accidente de camiones en la ruta 35. - Noticias Radio Reflejos","og_description":"En la tarde de este mi\u00e9rcoles alrededor de la hora 16.30, se produjo una violenta colisi\u00f3n en el kil\u00f3metro 63 de la ruta nacional 35 en jurisdicci\u00f3n del partido de Tornquist cuando dos camiones protagonizaron un accidente.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2017-12-14T11:30:11+00:00","og_image":[{"url":"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/","name":"Accidente de camiones en la ruta 35. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage"},"thumbnailUrl":"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg","datePublished":"2017-12-14T11:30:11+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#primaryimage","url":"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg","contentUrl":"http:\/\/farm5.staticflickr.com\/4580\/27272194729_e0c75471ca.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/accidente-de-camiones-en-la-ruta-35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Accidente de camiones en la ruta 35."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/17164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=17164"}],"version-history":[{"count":0,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/17164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=17164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=17164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=17164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}