{"id":129765,"date":"2025-12-14T20:40:18","date_gmt":"2025-12-14T23:40:18","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=129765"},"modified":"2025-12-15T09:51:58","modified_gmt":"2025-12-15T12:51:58","slug":"alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/","title":{"rendered":"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina."},"content":{"rendered":"<p>\u200bDe acuerdo a un informe de la Bolsa de Cereales y Productos de Bah\u00eda Blanca (BCPBB), rige un alerta de alto riesgo de incendios rurales en el sudoeste de la provincia, que se agudizar\u00e1 a partir del mi\u00e9rcoles 17 de diciembre.<\/p>\n<p><!--more--><\/p>\n<p>Las condiciones clim\u00e1ticas, que incluyen una intensa ola de calor con m\u00e1ximas que superar\u00e1n los 32 grados, junto con la estaci\u00f3n de cosecha en curso, han elevado significativamente el peligro en una amplia zona productiva, especialmente en la regi\u00f3n serrana.<br \/>\n\u200bLa advertencia rige especialmente a partir del martes 17 de diciembre y d\u00edas subsiguientes, considerados cr\u00edticos para la aparici\u00f3n y propagaci\u00f3n de siniestros rurales y forestales.<\/p>\n<h4>\n\u200bLos municipios con mayor riesgo de incendios<\/h4>\n<p>\u200bEl alerta es para un amplio sector que incluye los partidos de Bah\u00eda Blanca, Coronel Rosales, Villarino, Coronel Pringles, Coronel Dorrego, Tornquist, Saavedra, Puan, Coronel Su\u00e1rez, Adolfo Alsina, Guamin\u00ed, Tres Arroyos, Adolfo Gonz\u00e1les Chaves, Salliquel\u00f3 y San Cayetano.<br \/>\n\u200bSe hace un especial hincapi\u00e9 en la necesidad de extremar la precauci\u00f3n en el partido de Tornquist y el resto de la zona serrana, donde la combinaci\u00f3n de pastos secos, altas temperaturas y vientos puede acelerar la propagaci\u00f3n de cualquier foco \u00edgneo.<\/p>\n<h4>\u200bM\u00e1xima Precauci\u00f3n en la Cosecha Fina<\/h4>\n<p>\u200bAnte la coincidencia del riesgo elevado con la etapa de trilla en la regi\u00f3n, especialistas del sector agropecuario, incluyendo al INTA Bordenave, enfatizan la necesidad de extremar las medidas de prevenci\u00f3n para evitar que las maquinarias o la actividad agr\u00edcola provoquen focos \u00edgneos.<\/p>\n<h4>\u200bRecomendaciones esenciales para productores y contratistas<\/h4>\n<p>\u200bHorario de Labor: Evitar las labores de cosecha bajo condiciones ambientales de alto riesgo, concentrando el trabajo durante la ma\u00f1ana o la tarde y evitando las horas m\u00e1s calurosas del d\u00eda.<\/p>\n<p>\u200bLimpieza de Maquinaria: Es crucial limpiar con sopladoras las zonas cr\u00edticas (motor, tomas de aire y zonas de fricci\u00f3n) al menos tres veces al d\u00eda para prevenir la acumulaci\u00f3n de material inflamable como paja y granza.<br \/>\n\u200bMantenimiento: Reparar de inmediato fugas de aceite o gasoil en el motor.<\/p>\n<p>\u200bElementos de Extinci\u00f3n: Mantener extintores (preferentemente de polvo y alguno de agua) en las m\u00e1quinas y en los acoplados tolva para una respuesta r\u00e1pida.<\/p>\n<p>\u200bCondiciones Ambientales Cr\u00edticas: Evitar trabajar con temperaturas mayores a 30 grados, humedad relativa menor a 30% y una velocidad de viento promedio superior a 35 { Km\/h}.<\/p>\n<p>\u200bLas autoridades recuerdan que, de acuerdo con el sem\u00e1foro de peligro, el riesgo \u00abAlto\u00bb indica que solo est\u00e1 \u00ab<strong>Permitido hacer fuego solo en lugares habilitados\u00bb<\/strong>, mientras que el riesgo \u00abMuy Alto\u00bb o \u00abExtremo\u00bb implica que est\u00e1 \u00abProhibido hacer fuego en toda la provincia\u00bb.<br \/>\n\u200b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u200bDe acuerdo a un informe de la Bolsa de Cereales y Productos de Bah\u00eda Blanca (BCPBB), rige un alerta de alto riesgo de incendios rurales en el sudoeste de la provincia, que se agudizar\u00e1 a partir del mi\u00e9rcoles 17 de diciembre.<\/p>\n","protected":false},"author":3,"featured_media":105262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,26],"tags":[48],"class_list":["post-129765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-sociedad","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"\u200bDe acuerdo a un informe de la Bolsa de Cereales y Productos de Bah\u00eda Blanca (BCPBB), rige un alerta de alto riesgo de incendios rurales en el sudoeste de la provincia, que se agudizar\u00e1 a partir del mi\u00e9rcoles 17 de diciembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-14T23:40:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:51:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/\",\"name\":\"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg\",\"datePublished\":\"2025-12-14T23:40:18+00:00\",\"dateModified\":\"2025-12-15T12:51:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg\",\"width\":980,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/","og_locale":"es_ES","og_type":"article","og_title":"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos","og_description":"\u200bDe acuerdo a un informe de la Bolsa de Cereales y Productos de Bah\u00eda Blanca (BCPBB), rige un alerta de alto riesgo de incendios rurales en el sudoeste de la provincia, que se agudizar\u00e1 a partir del mi\u00e9rcoles 17 de diciembre.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-12-14T23:40:18+00:00","article_modified_time":"2025-12-15T12:51:58+00:00","og_image":[{"width":980,"height":640,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/","name":"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina. - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg","datePublished":"2025-12-14T23:40:18+00:00","dateModified":"2025-12-15T12:51:58+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/07\/Fuego-en-Cordoba.jpg","width":980,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/alerta-en-el-sudoeste-bonaerense-alto-riesgo-de-incendios-por-la-ola-de-calor-que-se-avecina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Alerta en el sudoeste bonaerense: Alto riesgo de incendios por la ola de calor que se avecina."}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/129765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=129765"}],"version-history":[{"count":4,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/129765\/revisions"}],"predecessor-version":[{"id":129792,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/129765\/revisions\/129792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/105262"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=129765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=129765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=129765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}