{"id":119110,"date":"2025-05-23T12:19:24","date_gmt":"2025-05-23T15:19:24","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=119110"},"modified":"2025-05-23T12:19:35","modified_gmt":"2025-05-23T15:19:35","slug":"el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/","title":{"rendered":"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez&#8230; espera a P\u00e9rez\u2019 llega a Tornquist"},"content":{"rendered":"<p>El domingo 8 de junio, en el Teatro Municipal \u2018Rodolfo Funke\u2019 de Tornquist, se presentar\u00e1 \u2018El Ratoncito P\u00e9rez\u2026 espera a P\u00e9rez\u2019, un espect\u00e1culo de la compa\u00f1\u00eda de Teatro de T\u00edteres Burbujas.<!--more--><\/p>\n<p><a data-flickr-embed=\"true\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/54538939562\/in\/dateposted-public\/\" title=\"Titeres burbujas (1)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/54538939562_24b3f45b35_z.jpg\" width=\"453\" height=\"640\" alt=\"Titeres burbujas (1)\"\/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n<p>El show, para ni\u00f1as y ni\u00f1os desde los 2 a\u00f1os y p\u00fablico familiar, comenzar\u00e1 a las 17 hs y recorrer\u00e1 una entra\u00f1able historia para disfrutar en familia.<\/p>\n<p>\u00bfQu\u00e9 pasa cuando, por primera vez, al mism\u00edsimo Ratoncito P\u00e9rez se le cae un diente? Una obra llena de humor, ternura y emoci\u00f3n, que invita a imaginar qu\u00e9 sucede cuando incluso los h\u00e9roes m\u00e1s peque\u00f1os necesitan ayuda. M\u00fasica original y canciones compuestas por Javier Dameson, que acompa\u00f1an y enriquecen la historia de principio a fin.<\/p>\n<p>Las entradas se encuentran a la venta en el Teatro y tienen un valor de $5.000.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 8 de junio, en el Teatro Municipal \u2018Rodolfo Funke\u2019 de Tornquist, se presentar\u00e1 \u2018El Ratoncito P\u00e9rez\u2026 espera a P\u00e9rez\u2019, un espect\u00e1culo de la compa\u00f1\u00eda de Teatro de T\u00edteres Burbujas.<\/p>\n","protected":false},"author":3,"featured_media":119111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-119110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El domingo 8 de junio, en el Teatro Municipal \u2018Rodolfo Funke\u2019 de Tornquist, se presentar\u00e1 \u2018El Ratoncito P\u00e9rez\u2026 espera a P\u00e9rez\u2019, un espect\u00e1culo de la compa\u00f1\u00eda de Teatro de T\u00edteres Burbujas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T15:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-23T15:19:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png\" \/>\n\t<meta property=\"og:image:width\" content=\"811\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/\",\"name\":\"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png\",\"datePublished\":\"2025-05-23T15:19:24+00:00\",\"dateModified\":\"2025-05-23T15:19:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png\",\"width\":811,\"height\":539},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez&#8230; espera a P\u00e9rez\u2019 llega a Tornquist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/","og_locale":"es_ES","og_type":"article","og_title":"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos","og_description":"El domingo 8 de junio, en el Teatro Municipal \u2018Rodolfo Funke\u2019 de Tornquist, se presentar\u00e1 \u2018El Ratoncito P\u00e9rez\u2026 espera a P\u00e9rez\u2019, un espect\u00e1culo de la compa\u00f1\u00eda de Teatro de T\u00edteres Burbujas.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-05-23T15:19:24+00:00","article_modified_time":"2025-05-23T15:19:35+00:00","og_image":[{"width":811,"height":539,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/","name":"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez... espera a P\u00e9rez\u2019 llega a Tornquist - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png","datePublished":"2025-05-23T15:19:24+00:00","dateModified":"2025-05-23T15:19:35+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/05\/Titeres-burbujas-2-e1748013551427.png","width":811,"height":539},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-espectaculo-de-titeres-el-ratoncito-perez-espera-a-perez-llega-a-tornquist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El espect\u00e1culo de t\u00edteres \u2018El Ratoncito P\u00e9rez&#8230; espera a P\u00e9rez\u2019 llega a Tornquist"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/119110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=119110"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/119110\/revisions"}],"predecessor-version":[{"id":119113,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/119110\/revisions\/119113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/119111"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=119110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=119110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=119110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}