{"id":116171,"date":"2025-05-06T18:28:41","date_gmt":"2025-05-06T21:28:41","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=116171"},"modified":"2025-05-06T18:31:54","modified_gmt":"2025-05-06T21:31:54","slug":"el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/","title":{"rendered":"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo"},"content":{"rendered":"<p>Seg\u00fan datos oficiales de la Secretar\u00eda de Turismo de Tornquist Municipio, los alojamientos habilitados alcanzaron un muy buen nivel de ocupaci\u00f3n, que estuvo entre el 46 y 91% dentro de las localidades de la comarca.<!--more--><\/p>\n<p>Se conocieron los datos oficiales del fin de semana largo que arranc\u00f3 el jueves 1\u00b0 de mayo. De acuerdo al cuadro estad\u00edstico, Saldungaray tuvo el menor porcentual, en tanto el m\u00e1ximo registrado lo tuvo Villa Serrana La Gruta con el 91%.<\/p>\n<p>Sierra de la Ventana lleg\u00f3 al 71% y Villa Ventana a un 67%. Tornquist alcanz\u00f3 el 80% mientras que el sector serrano de la Ruta 76 tuvo el 86%.<\/p>\n<p>Dentro del promedio, San Andres de las Sierras lleg\u00f3 al 54% . El promedio general di\u00f3 71% , un n\u00famero muy interesante y superador de muchos fines de semana largos anteriores.<\/p>\n<p><a title=\"Finde 1\u00b0 de mayo\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/54502373890\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/live.staticflickr.com\/65535\/54502373890_62743368bb_o.jpg\" alt=\"Finde 1\u00b0 de mayo\" width=\"387\" height=\"274\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos oficiales de la Secretar\u00eda de Turismo de Tornquist Municipio, los alojamientos habilitados alcanzaron un muy buen nivel de ocupaci\u00f3n, que estuvo entre el 46 y 91% dentro de las localidades de la comarca.<\/p>\n","protected":false},"author":3,"featured_media":75873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,33],"tags":[48],"class_list":["post-116171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","category-turismo","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan datos oficiales de la Secretar\u00eda de Turismo de Tornquist Municipio, los alojamientos habilitados alcanzaron un muy buen nivel de ocupaci\u00f3n, que estuvo entre el 46 y 91% dentro de las localidades de la comarca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T21:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T21:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/\",\"name\":\"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg\",\"datePublished\":\"2025-05-06T21:28:41+00:00\",\"dateModified\":\"2025-05-06T21:31:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/","og_locale":"es_ES","og_type":"article","og_title":"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos","og_description":"Seg\u00fan datos oficiales de la Secretar\u00eda de Turismo de Tornquist Municipio, los alojamientos habilitados alcanzaron un muy buen nivel de ocupaci\u00f3n, que estuvo entre el 46 y 91% dentro de las localidades de la comarca.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-05-06T21:28:41+00:00","article_modified_time":"2025-05-06T21:31:54+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/","name":"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg","datePublished":"2025-05-06T21:28:41+00:00","dateModified":"2025-05-06T21:31:54+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2022\/08\/Turismo-Cerro-Ventana.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-distrito-tuvo-el-71-de-ocupacion-durante-el-pasado-finde-largo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El distrito tuvo el 71% de ocupaci\u00f3n durante el pasado finde largo"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/116171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=116171"}],"version-history":[{"count":3,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/116171\/revisions"}],"predecessor-version":[{"id":116175,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/116171\/revisions\/116175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/75873"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=116171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=116171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=116171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}