{"id":114795,"date":"2025-04-01T15:26:15","date_gmt":"2025-04-01T18:26:15","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=114795"},"modified":"2025-04-01T15:26:15","modified_gmt":"2025-04-01T18:26:15","slug":"hcd-orden-del-dia-1-4-25","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/","title":{"rendered":"HCD: Orden del d\u00eda 1-4-25"},"content":{"rendered":"<p>El Honorable Concejo Deliberante comparte la orden del d\u00eda para la sesi\u00f3n con fecha 1 de abril, tomando lugar a las 16hs.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><b>Tornquist, 31 de marzo de 2025.-<\/b><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><b>Orden del D\u00eda<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>1.- Aprobaci\u00f3n del Acta N\u00ba 1350\/25.<\/b><span style=\"font-weight: 400;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><b>2.- Comunicaciones Oficiales: <\/b><span style=\"font-weight: 400;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Nota N\u00ba 49\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013 Solicita tratamiento con premura y urgencia del Expediente N\u00ba 142\/25.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 297\/23:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013 Autoriza la firma del Contrato de Locaci\u00f3n entre Oscar Juan Irigoyen y Zulema Nora Irigoyen con la Municipalidad de Tornquist.&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 99\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013 Cierre de Ejercicio 2024.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 125\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013 Convalida la firma del Contrato de Locaci\u00f3n celebrado entre Mar\u00eda Ester Fermanelli y la Municipalidad de Tornquist. S.E.A.T. Saldungaray.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 126\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013<\/span> <span style=\"font-weight: 400;\">Convalida la firma del Contrato de Locaci\u00f3n celebrado entre Luis Roberto Fiorentini y la Municipalidad de Tornquist &#8211; Departamento Interno.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 127\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013<\/span> <span style=\"font-weight: 400;\">Convalida la firma del Contrato de Locaci\u00f3n celebrado entre Luis Roberto Fiorentini y la Municipalidad de Tornquist &#8211; Departamento planta alta y baja.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 142\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. &#8211; Convalida la firma del Convenio celebrado entre Buenos Aires Gas S.A. y la Municipalidad de Tornquist. Obra Provisi\u00f3n de GLP Villa Ventana.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 144\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013<\/span> <span style=\"font-weight: 400;\">Autoriza la firma del Acta Complementaria N\u00ba 11 &#8211; Obra Instalaci\u00f3n El\u00e9ctrica Escuela T\u00e9cnica N\u00ba 1.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>3.- Dict\u00e1menes de las Comisiones<\/b><span style=\"font-weight: 400;\">: &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 598\/24:<\/b><span style=\"font-weight: 400;\"> &#8211;<\/span> <span style=\"font-weight: 400;\">D.E. &#8211; Autoriza la firma del Contrato de Locaci\u00f3n e\/la Municipalidad de Tornquist y Sitios Argentina S.A.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 112\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; Departamento Ejecutivo: Baja bienes f\u00edsicos 2025.&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 119\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; D.E. \u2013 Convalida la firma del Convenio Marco de Cooperaci\u00f3n cel. e\/la Universidad Nacional de General San Mart\u00edn y el Municipio de Tornquist.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 7857\/25:<\/b><span style=\"font-weight: 400;\"> &#8211;<\/span> <span style=\"font-weight: 400;\">Bloques Juntos y Juntos por el Cambio \u2013 Minuta de Comunicaci\u00f3n: Solicita al D.E. que env\u00ede a este Cuerpo las rendiciones de subsidios detallados en la misma.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 7859\/25:<\/b><span style=\"font-weight: 400;\"> &#8211;<\/span> <span style=\"font-weight: 400;\">Bloques Juntos y Juntos por el Cambio \u2013 Proyecto de Resoluci\u00f3n: Solicita la suspensi\u00f3n de toda intervenci\u00f3n en el predio \u201cLa Hoya\u201d de Sierra de la Ventana.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 7860\/25:<\/b><span style=\"font-weight: 400;\"> &#8211;<\/span> <span style=\"font-weight: 400;\">Bloques Frente de Todos y Uni\u00f3n por la Patria \u2013 Proyecto de Ordenanza: Placa de reconocimiento a ex Combatientes de Malvinas del Distrito.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 7861\/25:<\/b><span style=\"font-weight: 400;\"> &#8211;<\/span> <span style=\"font-weight: 400;\">Bloques Frente de Todos y Uni\u00f3n por la Patria \u2013 Proyecto de Resoluci\u00f3n: Solicita al D.E. colocaci\u00f3n de carteler\u00eda en Avenida Belgrano de puntos de inter\u00e9s tur\u00edstico.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">#<\/span><b>Expte. N\u00ba 7862\/25:<\/b><span style=\"font-weight: 400;\"> &#8211; Bloques Frente de Todos y Uni\u00f3n por la Patria \u2013 Proyecto de Ordenanza: Reconocimiento post mortem a Veteranos de Guerra de Malvinas.-<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>4.- Proyectos Presentados.<\/b><span style=\"font-weight: 400;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p><b>5.- Asuntos Particulares.<\/b><span style=\"font-weight: 400;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>D\u00eda de la Sesi\u00f3n:<\/b><span style=\"font-weight: 400;\"> 01 de abril de 2025.-<\/span><\/p>\n<p><b>Hora de Comienzo:<\/b><span style=\"font-weight: 400;\"> 16:00 Hs.-<\/span><\/p>\n<p><b>\u00a0\u00a0\u00a0\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Juliana C. Sgammini\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Carmen B. Soverchia\u00a0<\/b><\/p>\n<p><b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Secretaria\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Presidente\u00a0<\/b><\/p>\n<p><b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0H.C.D. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 H.C.D.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Honorable Concejo Deliberante comparte la orden del d\u00eda para la sesi\u00f3n con fecha 1 de abril, tomando lugar a las 16hs.<\/p>\n","protected":false},"author":3,"featured_media":101288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-114795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concejo-deliberante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"El Honorable Concejo Deliberante comparte la orden del d\u00eda para la sesi\u00f3n con fecha 1 de abril, tomando lugar a las 16hs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T18:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/\",\"name\":\"HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png\",\"datePublished\":\"2025-04-01T18:26:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HCD: Orden del d\u00eda 1-4-25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/","og_locale":"es_ES","og_type":"article","og_title":"HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos","og_description":"El Honorable Concejo Deliberante comparte la orden del d\u00eda para la sesi\u00f3n con fecha 1 de abril, tomando lugar a las 16hs.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-04-01T18:26:15+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/","name":"HCD: Orden del d\u00eda 1-4-25 - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png","datePublished":"2025-04-01T18:26:15+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/04\/hcdconcejodeliberantetqt.png","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/hcd-orden-del-dia-1-4-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"HCD: Orden del d\u00eda 1-4-25"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=114795"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114795\/revisions"}],"predecessor-version":[{"id":114796,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114795\/revisions\/114796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/101288"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=114795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=114795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=114795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}