{"id":114783,"date":"2025-04-01T15:16:29","date_gmt":"2025-04-01T18:16:29","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=114783"},"modified":"2025-04-01T15:29:03","modified_gmt":"2025-04-01T18:29:03","slug":"biblioteca-mariano-moreno-cambio-de-horarios","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/","title":{"rendered":"Biblioteca Mariano Moreno: cambio de horarios"},"content":{"rendered":"<p>A partir de abril, la biblioteca popular de Sierra de la Ventana estar\u00e1 abierta al p\u00fablico de Lunes a Viernes, de 10 a 19 hs.<!--more--><\/p>\n<p><a title=\"Horario de Verano 2025 - 2\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/54424865080\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/54424865080_517f04c7ab_b.jpg\" alt=\"Horario de Verano 2025 - 2\" width=\"1024\" height=\"1024\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de abril, la biblioteca popular de Sierra de la Ventana estar\u00e1 abierta al p\u00fablico de Lunes a Viernes, de 10 a 19 hs.<\/p>\n","protected":false},"author":3,"featured_media":108574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-114783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"A partir de abril, la biblioteca popular de Sierra de la Ventana estar\u00e1 abierta al p\u00fablico de Lunes a Viernes, de 10 a 19 hs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T18:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T18:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/\",\"name\":\"Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg\",\"datePublished\":\"2025-04-01T18:16:29+00:00\",\"dateModified\":\"2025-04-01T18:29:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca Mariano Moreno: cambio de horarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/","og_locale":"es_ES","og_type":"article","og_title":"Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos","og_description":"A partir de abril, la biblioteca popular de Sierra de la Ventana estar\u00e1 abierta al p\u00fablico de Lunes a Viernes, de 10 a 19 hs.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-04-01T18:16:29+00:00","article_modified_time":"2025-04-01T18:29:03+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/","name":"Biblioteca Mariano Moreno: cambio de horarios - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg","datePublished":"2025-04-01T18:16:29+00:00","dateModified":"2025-04-01T18:29:03+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/10\/Biblio-Mariano-Moreno.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/biblioteca-mariano-moreno-cambio-de-horarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Biblioteca Mariano Moreno: cambio de horarios"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=114783"}],"version-history":[{"count":3,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114783\/revisions"}],"predecessor-version":[{"id":114797,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114783\/revisions\/114797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/108574"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=114783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=114783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=114783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}