{"id":114398,"date":"2025-03-23T09:58:21","date_gmt":"2025-03-23T12:58:21","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=114398"},"modified":"2025-03-23T10:13:32","modified_gmt":"2025-03-23T13:13:32","slug":"domingo-en-la-macedonio-2","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/","title":{"rendered":"Domingo en la Macedonio"},"content":{"rendered":"<p>La Biblioteca Popular Macedonio Fern\u00e1ndez de Villa Ventana presenta un recital folcl\u00f3rico de \u00abMil Puentes\u00bb, para cantarle a la memoria.<!--more--><\/p>\n<p><a title=\"domingo en la Macedonio\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/54404948628\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/54404948628_e244d7cb90_c.jpg\" alt=\"domingo en la Macedonio\" width=\"800\" height=\"800\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Biblioteca Popular Macedonio Fern\u00e1ndez de Villa Ventana presenta un recital folcl\u00f3rico de \u00abMil Puentes\u00bb, para cantarle a la memoria.<\/p>\n","protected":false},"author":3,"featured_media":114400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-114398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Domingo en la Macedonio - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domingo en la Macedonio - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La Biblioteca Popular Macedonio Fern\u00e1ndez de Villa Ventana presenta un recital folcl\u00f3rico de \u00abMil Puentes\u00bb, para cantarle a la memoria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-23T12:58:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-23T13:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/\",\"name\":\"Domingo en la Macedonio - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg\",\"datePublished\":\"2025-03-23T12:58:21+00:00\",\"dateModified\":\"2025-03-23T13:13:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg\",\"width\":1080,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domingo en la Macedonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domingo en la Macedonio - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/","og_locale":"es_ES","og_type":"article","og_title":"Domingo en la Macedonio - Noticias Radio Reflejos","og_description":"La Biblioteca Popular Macedonio Fern\u00e1ndez de Villa Ventana presenta un recital folcl\u00f3rico de \u00abMil Puentes\u00bb, para cantarle a la memoria.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2025-03-23T12:58:21+00:00","article_modified_time":"2025-03-23T13:13:32+00:00","og_image":[{"width":1080,"height":674,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/","name":"Domingo en la Macedonio - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg","datePublished":"2025-03-23T12:58:21+00:00","dateModified":"2025-03-23T13:13:32+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2025\/03\/domingo-en-la-Macedonio.jpg","width":1080,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/domingo-en-la-macedonio-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Domingo en la Macedonio"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=114398"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114398\/revisions"}],"predecessor-version":[{"id":114399,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/114398\/revisions\/114399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/114400"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=114398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=114398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=114398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}