{"id":105012,"date":"2024-07-15T14:59:10","date_gmt":"2024-07-15T17:59:10","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=105012"},"modified":"2024-07-15T14:59:10","modified_gmt":"2024-07-15T17:59:10","slug":"vuelve-el-freestyle-a-la-comarca","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/","title":{"rendered":"Vuelve el freestyle a la comarca"},"content":{"rendered":"<p>Este mi\u00e9rcoles habr\u00e1 batallas en la plaza San Bernardo. \u201cLa idea es poner una semillita para la cultura hip hop\u201d asegur\u00f3 Bruno Mend\u00eda, su organizador.<!--more--><\/p>\n<p>Este mi\u00e9rcoles en la plaza San Bernardo se dar\u00e1 una competencia de freestyle, retomando una actividad que en la comarca estuvo parada por cuatro a\u00f1os.<\/p>\n<p>Al respecto Bruno Mend\u00eda, su organizador, explic\u00f3 que \u201cesto fue una ocurrencia m\u00eda. Tengo ganas que venga gente a disfrutar, ya sea de ac\u00e1 o no. Es una competencia de freestyle, que arrancar\u00e1 a las 15 hs. De premio habr\u00e1 diez mil pesos, m\u00e1s una producci\u00f3n y un corte de pelo\u201d.<\/p>\n<p>Seg\u00fan dijo \u201cla idea es poner una semillita para la cultura hip hop de la comarca. Esto est\u00e1 apuntado a los chicos que est\u00e1n empezando y esto los puede ayudar. Fluy\u00f3 as\u00ed. Fui a hablar con la delegada, le plante\u00e9 de hacerlo en una plaza que muchas veces no recibe eventos, est\u00e1 bien ubicada, y puede tener mucha gente por estar en vacaciones\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Dando m\u00e1s detalles de la actividad, sostuvo que \u201ctenemos sonido para poner ese d\u00eda, habr\u00e1 micr\u00f3fonos. Vendr\u00e1n de la zona, de Bah\u00eda. La intenci\u00f3n es que salga algo lindo y disfrutar el momento. No estoy pensando tanto en la gente que pueda ir, sino que el evento salga prolijo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Haciendo un poco de historia, \u201cLa Guerrilla es la compe de un amigo y es una gran referencia, porque antes de eso no hubo nada. Actualmente no est\u00e1 activo, as\u00ed que ahora no hay nada en Villa. Por eso la idea y las ganas de hacer algo nuevo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo subrayo que esta acci\u00f3n es \u201ctotalmente gratuita la inscripci\u00f3n. La compe iniciar\u00e1 a las 15:30. Solo hay que tener ganas de competir. Se pueden anotar en mi instagram Meendi.B, en la misma compe se pueden anotar o sino por WhatsApp al 2915270392\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1872218883&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"fmreflejos 103.7\" href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\" target=\"_blank\" rel=\"noopener\">fmreflejos 103.7<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"Bruno Mend\u00eda 15 - 7\" href=\"https:\/\/soundcloud.com\/fmreflejos-103-7\/bruno-menbia-15-7\" target=\"_blank\" rel=\"noopener\">Bruno Mend\u00eda 15 &#8211; 7<\/a><\/div>\n<p>&nbsp;<\/p>\n<p><a title=\"SANBER\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/53859201279\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/53859201279_2e1fd183d5_z.jpg\" alt=\"SANBER\" width=\"452\" height=\"640\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles habr\u00e1 batallas en la plaza San Bernardo. \u201cLa idea es poner una semillita para la cultura hip hop\u201d asegur\u00f3 Bruno Mend\u00eda, su organizador.<\/p>\n","protected":false},"author":3,"featured_media":99437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-105012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vuelve el freestyle a la comarca - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vuelve el freestyle a la comarca - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Este mi\u00e9rcoles habr\u00e1 batallas en la plaza San Bernardo. \u201cLa idea es poner una semillita para la cultura hip hop\u201d asegur\u00f3 Bruno Mend\u00eda, su organizador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-15T17:59:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/\",\"name\":\"Vuelve el freestyle a la comarca - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg\",\"datePublished\":\"2024-07-15T17:59:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg\",\"width\":2560,\"height\":1206},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vuelve el freestyle a la comarca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vuelve el freestyle a la comarca - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/","og_locale":"es_ES","og_type":"article","og_title":"Vuelve el freestyle a la comarca - Noticias Radio Reflejos","og_description":"Este mi\u00e9rcoles habr\u00e1 batallas en la plaza San Bernardo. \u201cLa idea es poner una semillita para la cultura hip hop\u201d asegur\u00f3 Bruno Mend\u00eda, su organizador.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2024-07-15T17:59:10+00:00","og_image":[{"width":2560,"height":1206,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/","name":"Vuelve el freestyle a la comarca - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg","datePublished":"2024-07-15T17:59:10+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/02\/Sierra-de-la-Ventana--scaled.jpg","width":2560,"height":1206},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/vuelve-el-freestyle-a-la-comarca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Vuelve el freestyle a la comarca"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/105012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=105012"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/105012\/revisions"}],"predecessor-version":[{"id":105033,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/105012\/revisions\/105033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/99437"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=105012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=105012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=105012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}