{"id":104646,"date":"2024-07-04T14:35:20","date_gmt":"2024-07-04T17:35:20","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=104646"},"modified":"2024-07-04T14:48:22","modified_gmt":"2024-07-04T17:48:22","slug":"invitacion-al-acto-oficial-por-el-dia-de-la-independencia","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/","title":{"rendered":"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia"},"content":{"rendered":"<p>La intendenta interina Estefan\u00eda Bordoni, invita a la comunidad al acto oficial por el D\u00eda de la Independencia, a realizarse el martes 9 de julio a las 10 hs en el Teatro Municipal \u2018Rodolfo Funke\u2019.<!--more--><\/p>\n<p><a data-flickr-embed=\"true\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/53835309668\/in\/dateposted-public\/\" title=\"9 de julio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png\" width=\"1080\" height=\"1350\" alt=\"9 de julio\"\/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La jornada contar\u00e1 con la actuaci\u00f3n de la Escuela Folkl\u00f3rica Municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intendenta interina Estefan\u00eda Bordoni, invita a la comunidad al acto oficial por el D\u00eda de la Independencia, a realizarse el martes 9 de julio a las 10 hs en el Teatro Municipal \u2018Rodolfo Funke\u2019.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-104646","post","type-post","status-publish","format-standard","hentry","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"La intendenta interina Estefan\u00eda Bordoni, invita a la comunidad al acto oficial por el D\u00eda de la Independencia, a realizarse el martes 9 de julio a las 10 hs en el Teatro Municipal \u2018Rodolfo Funke\u2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T17:35:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T17:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/\",\"name\":\"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png\",\"datePublished\":\"2024-07-04T17:35:20+00:00\",\"dateModified\":\"2024-07-04T17:48:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage\",\"url\":\"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png\",\"contentUrl\":\"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/","og_locale":"es_ES","og_type":"article","og_title":"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos","og_description":"La intendenta interina Estefan\u00eda Bordoni, invita a la comunidad al acto oficial por el D\u00eda de la Independencia, a realizarse el martes 9 de julio a las 10 hs en el Teatro Municipal \u2018Rodolfo Funke\u2019.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2024-07-04T17:35:20+00:00","article_modified_time":"2024-07-04T17:48:22+00:00","og_image":[{"url":"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png","type":"","width":"","height":""}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/","name":"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage"},"thumbnailUrl":"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png","datePublished":"2024-07-04T17:35:20+00:00","dateModified":"2024-07-04T17:48:22+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#primaryimage","url":"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png","contentUrl":"https:\/\/live.staticflickr.com\/65535\/53835309668_3ec49dd10d_o.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/invitacion-al-acto-oficial-por-el-dia-de-la-independencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Invitaci\u00f3n al acto oficial por el D\u00eda de la Independencia"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=104646"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104646\/revisions"}],"predecessor-version":[{"id":104648,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104646\/revisions\/104648"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=104646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=104646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=104646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}