{"id":104447,"date":"2024-06-28T21:12:10","date_gmt":"2024-06-29T00:12:10","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=104447"},"modified":"2024-06-28T21:12:10","modified_gmt":"2024-06-29T00:12:10","slug":"concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/","title":{"rendered":"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray"},"content":{"rendered":"<div dir=\"auto\">En la ma\u00f1ana del 28 de junio. Mantuvieron una reuni\u00f3n con el Delegado Municipal, Sr. Gerardo Rohlmann y el Subsecretario de Desarrollo Social, Sr. Facundo Pereyra.<\/div>\n<p><!--more--><\/p>\n<div dir=\"auto\">En la recorrida visitaron las futuras instalaciones del geri\u00e1trico Municipal y dialogaron con vecinos de la localidad.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del 28 de junio. Mantuvieron una reuni\u00f3n con el Delegado Municipal, Sr. Gerardo Rohlmann y el Subsecretario de Desarrollo Social, Sr. Facundo Pereyra.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-104447","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"En la ma\u00f1ana del 28 de junio. Mantuvieron una reuni\u00f3n con el Delegado Municipal, Sr. Gerardo Rohlmann y el Subsecretario de Desarrollo Social, Sr. Facundo Pereyra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-29T00:12:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/Concejales-de-UcR-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/\",\"name\":\"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2024-06-29T00:12:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/","og_locale":"es_ES","og_type":"article","og_title":"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos","og_description":"En la ma\u00f1ana del 28 de junio. Mantuvieron una reuni\u00f3n con el Delegado Municipal, Sr. Gerardo Rohlmann y el Subsecretario de Desarrollo Social, Sr. Facundo Pereyra.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2024-06-29T00:12:10+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/Concejales-de-UcR-3.webp","type":"image\/webp"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/","name":"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2024-06-29T00:12:10+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/concejales-de-los-bloques-juntos-y-jxc-ucr-la-localidad-de-saldungaray\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"Concejales de los Bloques Juntos y JxC-UCR la localidad de Saldungaray"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=104447"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104447\/revisions"}],"predecessor-version":[{"id":104449,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/104447\/revisions\/104449"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=104447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=104447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=104447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}