{"id":103723,"date":"2024-06-10T08:23:19","date_gmt":"2024-06-10T11:23:19","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=103723"},"modified":"2024-06-10T08:57:30","modified_gmt":"2024-06-10T11:57:30","slug":"la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/","title":{"rendered":"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial"},"content":{"rendered":"<p>No hay que atender por WhatsApp llamadas de n\u00fameros desconocidos, sobre todo del exterior.<!--more--><\/p>\n<p>Hay una nueva forma de estafar que se est\u00e1 expandiendo por todo el mundo y, claro est\u00e1, tambi\u00e9n est\u00e1 llegando a la Argentina: clonan voces y la usan para enviar mensajes por WhatsApp pidiendo dinero u alg\u00fan otro tipo de maniobra fraudulenta.<\/p>\n<p>Es la estafa conocida como vishing y en todo el pa\u00eds se est\u00e1n registrando casos, con situaciones que son muy complicadas de detener.<\/p>\n<p>Inteligencia Artificial para estafar<br \/>\nEn la ciudad de Mar del Plata, el abogado Rodrigo Bionda, especialista en la prevenci\u00f3n de ciberdelitos, dio recomendaciones para estar atentos a las maniobras sofisticadas vinculadas a la inteligencia artificial.<\/p>\n<p>\u00abDebemos empezar a descreer de todo lo que vemos y escuchamos\u00bb, indic\u00f3 el especialista.<\/p>\n<p>No hay que atender llamados provenientes de la India<\/p>\n<p>\u00abSi la grabaci\u00f3n ronda el medio minuto ya ser\u00eda imposible darse cuenta si es real o no. \u00abHice una prueba de videollamada con una versi\u00f3n paga de inteligencia artificial y es imposible darse cuenta si estamos frente a la persona original\u00bb, explic\u00f3 el abogado.<\/p>\n<p>El t\u00e9rmino deriva de la uni\u00f3n de dos palabras: &#8216;voice&#8217; y &#8216;phishing&#8217; y se refiere al tipo de amenaza que combina una llamada telef\u00f3nica fraudulenta con informaci\u00f3n previamente obtenida desde internet.<\/p>\n<p>Las estafas con voces clonadas por inteligencia artificial (IA) representan un tipo de ciberataque que utiliza esta tecnolog\u00eda para clonar voces, suplantando la identidad de familiares o amigos para enga\u00f1ar a sus v\u00edctimas.<\/p>\n<p>Seg\u00fan una encuesta reciente realizada por McAfee, el 77% de las v\u00edctimas de esta modalidad de fraude terminaron enviando dinero.<\/p>\n<p>&nbsp;<\/p>\n<p><a title=\"estafa x wsp\" href=\"https:\/\/www.flickr.com\/photos\/182279889@N02\/53780671557\/in\/dateposted-public\/\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/live.staticflickr.com\/31337\/53780671557_d540d846c4_o.jpg\" alt=\"estafa x wsp\" width=\"640\" height=\"360\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n<p>\u00a1ALERTA ESTAFAS!: CLONAN VOCES CON INTELIGENCIA ARTIFICIAL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay que atender por WhatsApp llamadas de n\u00fameros desconocidos, sobre todo del exterior.<\/p>\n","protected":false},"author":3,"featured_media":103730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,26],"tags":[48],"class_list":["post-103723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-sociedad","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"No hay que atender por WhatsApp llamadas de n\u00fameros desconocidos, sobre todo del exterior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T11:23:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T11:57:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/\",\"name\":\"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg\",\"datePublished\":\"2024-06-10T11:23:19+00:00\",\"dateModified\":\"2024-06-10T11:57:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg\",\"contentUrl\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg\",\"width\":630,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/","og_locale":"es_ES","og_type":"article","og_title":"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos","og_description":"No hay que atender por WhatsApp llamadas de n\u00fameros desconocidos, sobre todo del exterior.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2024-06-10T11:23:19+00:00","article_modified_time":"2024-06-10T11:57:30+00:00","og_image":[{"width":630,"height":360,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg","type":"image\/jpeg"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/","name":"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage"},"image":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg","datePublished":"2024-06-10T11:23:19+00:00","dateModified":"2024-06-10T11:57:30+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#primaryimage","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg","contentUrl":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2024\/06\/estafa-IA-WSP.jpg","width":630,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/la-nueva-estafa-por-whatsapp-que-hace-estragos-clonan-voces-con-la-inteligencia-artificial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"La nueva estafa por WhatsApp que hace estragos: clonan voces con la Inteligencia Artificial"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/103723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=103723"}],"version-history":[{"count":2,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/103723\/revisions"}],"predecessor-version":[{"id":103737,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/103723\/revisions\/103737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media\/103730"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=103723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=103723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=103723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}