{"id":102325,"date":"2024-05-08T15:17:51","date_gmt":"2024-05-08T18:17:51","guid":{"rendered":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?p=102325"},"modified":"2024-05-08T15:17:51","modified_gmt":"2024-05-08T18:17:51","slug":"el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes","status":"publish","type":"post","link":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/","title":{"rendered":"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes"},"content":{"rendered":"<p>Trabajadores del Grupo Dota no van a adherir a la medida y 43 l\u00edneas prestar\u00e1n servicio.<br \/>\n<!--more--><\/p>\n<p>El paro de la Confederaci\u00f3n General del Trabajo (CGT) previsto para ma\u00f1ana jueves afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que habitualmente se movilizan en colectivos y trenes.<\/p>\n<p>S\u00f3lo en el \u00c1rea Metropolitana de Buenos Aires (AMBA), alrededor de 4 millones de personas no podr\u00e1n trasladarse en colectivo; mientras que por el paro de los servicios de trenes metropolitanos, regionales y de media y larga distancia, cerca de 1 mill\u00f3n de personas se ver\u00e1n afectadas.<\/p>\n<p>En tanto, y teniendo en cuenta las 60 localidades del pa\u00eds que tienen el sistema SUBE, ser\u00e1n alrededor de 1.5 millones de personas las que habitualmente utilizan el colectivo en el interior del pa\u00eds y por el paro no podr\u00e1n hacerlo.<\/p>\n<p>\u00abLa decisi\u00f3n de la CGT afectar\u00e1 a 6.593.000 personas que ma\u00f1ana no van a tener a disposici\u00f3n el servicio esencial de transporte para ir a sus trabajos. Unas 4 millones de personas no van a poder viajar en colectivo en el AMBA y un mill\u00f3n y medio en el interior del pa\u00eds. Un mill\u00f3n de personas no van a poder viajar en trenes, y hay 93 mil personas que ver\u00e1n cancelados sus 703 vuelos. Y quiero aclarar que se encuentra abierta la l\u00ednea 134 para denunciar extorsiones\u00bb, declar\u00f3 el vocero Presidencial, Manuel Adorni.<\/p>\n<p>Y agreg\u00f3: \u00abNuestro Gobierno ya tuvo dos paros generales de la CGT, dos paros de colectivos, dos paros docentes, un paro de trenes, un paro aeron\u00e1utico y m\u00e1s de 100 marchas e intentos de piquete. En 4 a\u00f1os de gobierno de Alberto Fern\u00e1ndez, que termin\u00f3 con 211 por ciento de inflaci\u00f3n, 50 por ciento de pobres y 130 mil muertos bajo el lema el Estado te cuida, hubo cero paros\u00bb.<\/p>\n<h4>El paro tambi\u00e9n afectar\u00e1 703 vuelos que ya fueron cancelados en los que iban a viajar alrededor de 93 mil pasajeros.<\/h4>\n<h4>Colectivos que funcionar\u00e1n en el AMBA<\/h4>\n<p>A pesar de las medidas anunciadas p\u00fablicamente por la UTA, hay trabajadores pertenecientes al Grupo Dota que no van a adherir al paro, y ser\u00e1n 43 las l\u00edneas que prestar\u00e1n servicio.<\/p>\n<p>As\u00ed, las l\u00edneas que circular\u00e1n con sus respectivos recorridos ser\u00e1n: 6, 7, 8, 9, 12, 20, 21, 23, 24, 25, 28, 31, 44, 50, 51, 56, 57, 74, 76, 78, 79, 84, 87, 91, 99, 100, 101, 106, 107, 108, 111, 115, 117, 127, 130, 134, 135, 146, 150, 161, 164, 177 y 188.<\/p>\n<h4><\/h4>\n<h4>Acci\u00f3n de Transporte y Seguridad<\/h4>\n<p>Para garantizar el derecho a trabajar de los choferes de colectivos y de quien necesita transportarse para no perder su jornada de trabajo, la Secretar\u00eda de Transporte inform\u00f3 que coordin\u00f3 con el Ministerio de Seguridad el despliegue de efectivos policiales, m\u00f3viles y agentes, que estar\u00e1n distribuidos en puntos estrat\u00e9gicos de riesgo, asegurando las condiciones de seguridad para que puedan transitar sin problemas.<\/p>\n<p>Tambi\u00e9n habr\u00e1 personal de la Comisi\u00f3n Nacional de Regulaci\u00f3n del Transporte (CNRT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajadores del Grupo Dota no van a adherir a la medida y 43 l\u00edneas prestar\u00e1n servicio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-102325","post","type-post","status-publish","format-standard","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos\" \/>\n<meta property=\"og:description\" content=\"Trabajadores del Grupo Dota no van a adherir a la medida y 43 l\u00edneas prestar\u00e1n servicio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Radio Reflejos\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T18:17:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arnaldo Botto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/\",\"name\":\"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos\",\"isPartOf\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\"},\"datePublished\":\"2024-05-08T18:17:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website\",\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/\",\"name\":\"Noticias Radio Reflejos\",\"description\":\"Las noticias de mi comarca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1\",\"name\":\"Arnaldo Botto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g\",\"caption\":\"Arnaldo Botto\"},\"url\":\"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/","og_locale":"es_ES","og_type":"article","og_title":"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos","og_description":"Trabajadores del Grupo Dota no van a adherir a la medida y 43 l\u00edneas prestar\u00e1n servicio.","og_url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/","og_site_name":"Noticias Radio Reflejos","article_published_time":"2024-05-08T18:17:51+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-content\/uploads\/2021\/07\/logosol300x200.png","type":"image\/png"}],"author":"Arnaldo Botto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/","name":"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes - Noticias Radio Reflejos","isPartOf":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website"},"datePublished":"2024-05-08T18:17:51+00:00","author":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1"},"breadcrumb":{"@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/el-paro-de-la-cgt-afectara-a-mas-de-6-millones-y-medio-de-personas-que-se-movilizan-en-colectivos-y-trenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/"},{"@type":"ListItem","position":2,"name":"El paro de la CGT afectar\u00e1 a m\u00e1s de 6 millones y medio de personas que se movilizan en colectivos y trenes"}]},{"@type":"WebSite","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#website","url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/","name":"Noticias Radio Reflejos","description":"Las noticias de mi comarca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/ad82545263dcc5ec0996818884fd5fb1","name":"Arnaldo Botto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55cb5e37c1efa326397366e6974cb338056df65cb50e7d64d1cf314e87504837?s=96&d=mm&r=g","caption":"Arnaldo Botto"},"url":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/author\/arnaldo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/102325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/comments?post=102325"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/102325\/revisions"}],"predecessor-version":[{"id":102327,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/posts\/102325\/revisions\/102327"}],"wp:attachment":[{"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/media?parent=102325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/categories?post=102325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasradioreflejos.com.ar\/2021\/wp-json\/wp\/v2\/tags?post=102325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}